{"id":58,"date":"2025-05-12T16:59:21","date_gmt":"2025-05-12T13:59:21","guid":{"rendered":"https:\/\/dive-greece.3ds.gr\/?page_id=58"},"modified":"2025-12-22T07:06:11","modified_gmt":"2025-12-22T05:06:11","slug":"about-us","status":"publish","type":"page","link":"https:\/\/dive-greece.gr\/fr\/about-us\/","title":{"rendered":"A propos de nous"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"58\" class=\"elementor elementor-58\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-acd04fb e-con-full e-flex e-con e-parent\" data-id=\"acd04fb\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-37ac958 elementor-widget elementor-widget-jet-engine-component-807\" data-id=\"37ac958\" data-element_type=\"widget\" data-widget_type=\"jet-engine-component-807.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>.elementor-807 .elementor-element.elementor-element-ad6c42e{--display:flex;--min-height:92vh;--flex-direction:column;--container-widget-width:calc( ( 1 - var( --container-widget-flex-grow ) ) * 100% );--container-widget-height:initial;--container-widget-flex-grow:0;--container-widget-align-self:initial;--flex-wrap-mobile:wrap;--justify-content:center;--align-items:flex-start;--gap:1.25vw 1.25vw;--row-gap:1.25vw;--column-gap:1.25vw;--overlay-opacity:1;--padding-top:0;--padding-bottom:0;--padding-left:clamp(2.5rem, -3.2263rem + 8.9385vw, 7.5rem);--padding-right:clamp(2.5rem, -3.2263rem + 8.9385vw, 7.5rem);}.elementor-807 .elementor-element.elementor-element-ad6c42e::before, .elementor-807 .elementor-element.elementor-element-ad6c42e > .elementor-background-video-container::before, .elementor-807 .elementor-element.elementor-element-ad6c42e > .e-con-inner > .elementor-background-video-container::before, .elementor-807 .elementor-element.elementor-element-ad6c42e > .elementor-background-slideshow::before, .elementor-807 .elementor-element.elementor-element-ad6c42e > .e-con-inner > .elementor-background-slideshow::before, .elementor-807 .elementor-element.elementor-element-ad6c42e > .elementor-motion-effects-container > .elementor-motion-effects-layer::before{background-image:url(\"https:\/\/dive-greece.gr\/wp-content\/uploads\/Shape-Bacground-PERIOXH-Desktop.svg\");--background-overlay:'';background-position:bottom center;background-repeat:no-repeat;background-size:100% auto;}.elementor-807 .elementor-element.elementor-element-ad6c42e:not(.elementor-motion-effects-element-type-background), .elementor-807 .elementor-element.elementor-element-ad6c42e > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-position:center center;background-repeat:no-repeat;background-size:cover;}.elementor-widget-icon-list .elementor-icon-list-item:not(:last-child):after{border-color:var( --e-global-color-text );}.elementor-widget-icon-list .elementor-icon-list-icon i{color:var( --e-global-color-primary );}.elementor-widget-icon-list .elementor-icon-list-icon svg{fill:var( --e-global-color-primary );}.elementor-widget-icon-list .elementor-icon-list-item > .elementor-icon-list-text, .elementor-widget-icon-list .elementor-icon-list-item > a{font-family:var( --e-global-typography-text-font-family ), Sans-serif;font-size:var( --e-global-typography-text-font-size );font-weight:var( --e-global-typography-text-font-weight );line-height:var( --e-global-typography-text-line-height );}.elementor-widget-icon-list .elementor-icon-list-text{color:var( --e-global-color-secondary );}.elementor-807 .elementor-element.elementor-element-51f8d95 .elementor-icon-list-icon i{transition:color 0.3s;}.elementor-807 .elementor-element.elementor-element-51f8d95 .elementor-icon-list-icon svg{transition:fill 0.3s;}.elementor-807 .elementor-element.elementor-element-51f8d95{--e-icon-list-icon-size:clamp(2.1875rem, 1.79rem + 0.6204vw, 2.5345625rem);--icon-vertical-align:flex-start;--icon-vertical-offset:0px;}.elementor-807 .elementor-element.elementor-element-51f8d95 .elementor-icon-list-icon{padding-inline-end:0px;}.elementor-807 .elementor-element.elementor-element-51f8d95 .elementor-icon-list-item > .elementor-icon-list-text, .elementor-807 .elementor-element.elementor-element-51f8d95 .elementor-icon-list-item > a{font-family:var( --e-global-typography-c7efc90-font-family ), Sans-serif;font-size:var( --e-global-typography-c7efc90-font-size );font-weight:var( --e-global-typography-c7efc90-font-weight );line-height:var( --e-global-typography-c7efc90-line-height );}.elementor-807 .elementor-element.elementor-element-51f8d95 .elementor-icon-list-text{color:var( --e-global-color-primary );transition:color 0.3s;}.elementor-widget-heading .elementor-heading-title{font-family:var( --e-global-typography-primary-font-family ), Sans-serif;font-weight:var( --e-global-typography-primary-font-weight );color:var( --e-global-color-primary );}.elementor-807 .elementor-element.elementor-element-5aa5220 .elementor-heading-title{font-family:var( --e-global-typography-3e216f6-font-family ), Sans-serif;font-size:var( --e-global-typography-3e216f6-font-size );font-weight:var( --e-global-typography-3e216f6-font-weight );font-style:var( --e-global-typography-3e216f6-font-style );line-height:var( --e-global-typography-3e216f6-line-height );}.elementor-807 .elementor-element.elementor-element-539e06b > .elementor-widget-container{margin:0px 0px 0px 0px;}body:not(.rtl) .elementor-807 .elementor-element.elementor-element-539e06b{left:0px;}body.rtl .elementor-807 .elementor-element.elementor-element-539e06b{right:0px;}.elementor-807 .elementor-element.elementor-element-539e06b{top:122px;}@media(max-width:1024px){.elementor-widget-icon-list .elementor-icon-list-item > .elementor-icon-list-text, .elementor-widget-icon-list .elementor-icon-list-item > a{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}.elementor-807 .elementor-element.elementor-element-51f8d95 .elementor-icon-list-item > .elementor-icon-list-text, .elementor-807 .elementor-element.elementor-element-51f8d95 .elementor-icon-list-item > a{font-size:var( --e-global-typography-c7efc90-font-size );line-height:var( --e-global-typography-c7efc90-line-height );}.elementor-807 .elementor-element.elementor-element-5aa5220 .elementor-heading-title{font-size:var( --e-global-typography-3e216f6-font-size );line-height:var( --e-global-typography-3e216f6-line-height );}}@media(max-width:767px){.elementor-807 .elementor-element.elementor-element-ad6c42e::before, .elementor-807 .elementor-element.elementor-element-ad6c42e > .elementor-background-video-container::before, .elementor-807 .elementor-element.elementor-element-ad6c42e > .e-con-inner > .elementor-background-video-container::before, .elementor-807 .elementor-element.elementor-element-ad6c42e > .elementor-background-slideshow::before, .elementor-807 .elementor-element.elementor-element-ad6c42e > .e-con-inner > .elementor-background-slideshow::before, .elementor-807 .elementor-element.elementor-element-ad6c42e > .elementor-motion-effects-container > .elementor-motion-effects-layer::before{background-image:url(\"https:\/\/dive-greece.gr\/wp-content\/uploads\/Shape-Bacground-PERIOXH-Mobile.svg\");}.elementor-807 .elementor-element.elementor-element-ad6c42e{--min-height:85vh;--gap:10px 10px;--row-gap:10px;--column-gap:10px;--padding-top:20px;--padding-bottom:20px;--padding-left:20px;--padding-right:20px;}.elementor-widget-icon-list .elementor-icon-list-item > .elementor-icon-list-text, .elementor-widget-icon-list .elementor-icon-list-item > a{font-size:var( --e-global-typography-text-font-size );line-height:var( --e-global-typography-text-line-height );}.elementor-807 .elementor-element.elementor-element-51f8d95{--e-icon-list-icon-size:20px;}.elementor-807 .elementor-element.elementor-element-51f8d95 .elementor-icon-list-item > .elementor-icon-list-text, .elementor-807 .elementor-element.elementor-element-51f8d95 .elementor-icon-list-item > a{font-size:var( --e-global-typography-c7efc90-font-size );line-height:var( --e-global-typography-c7efc90-line-height );}.elementor-807 .elementor-element.elementor-element-5aa5220 .elementor-heading-title{font-size:var( --e-global-typography-3e216f6-font-size );line-height:var( --e-global-typography-3e216f6-line-height );}.elementor-807 .elementor-element.elementor-element-539e06b{top:75px;}}@media(min-width:768px){.elementor-807 .elementor-element.elementor-element-ad6c42e{--width:100%;}}\/* Start custom CSS for container, class: .elementor-element-ad6c42e *\/\/*Hero*\/\n\n    \/*Svg Hero*\/\n.hero-main span.elementor-icon-list-text {\n    \/*align-self: unset !important;*\/\n    padding: 0px 0px 0px 8px !IMPORTANT;\n}\n\n.hero-main svg {\n    margin: 0px ! IMPORTANT;\n}\n    \/*End Svg Hero*\/\n\n\/*End Hero*\/\n\n.elementor-807 .elementor-element.elementor-element-ad6c42e{\n    transition: all 0s !Important\n}\/* End custom CSS *\/<\/style><style type=\"text\/css\">.jet-component-instance-4603.jet-listing-grid--807 .elementor-element.elementor-element-ad6c42e:not(.elementor-motion-effects-element-type-background), .jet-component-instance-4603.jet-listing-grid--807 .elementor-element.elementor-element-ad6c42e > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/dive-greece.gr\/wp-content\/uploads\/\u03a3\u03b7\u03bc\u03b5\u03af\u03b1-\u039a\u03b1\u03c4\u03ac\u03b4\u03c5\u03c3\u03b7\u03c2-Bacground-Desktop.webp\");}@media(max-width:767px){.jet-component-instance-4603.jet-listing-grid--807 .elementor-element.elementor-element-ad6c42e:not(.elementor-motion-effects-element-type-background), .jet-component-instance-4603.jet-listing-grid--807 .elementor-element.elementor-element-ad6c42e > .elementor-motion-effects-container > .elementor-motion-effects-layer{background-image:url(\"https:\/\/dive-greece.gr\/wp-content\/uploads\/\u03a3\u03b7\u03bc\u03b5\u03af\u03b1-\u039a\u03b1\u03c4\u03ac\u03b4\u03c5\u03c3\u03b7\u03c2-Bacground-Mobile.webp\");}}<\/style>\t\t<div data-elementor-type=\"jet-engine-component\" data-elementor-id=\"807\" class=\"elementor elementor-807 jet-listing-grid--807 jet-component-instance-4603\" data-elementor-post-type=\"jet-engine\" style=\"\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ad6c42e e-con-full hero-main e-flex e-con e-parent\" data-id=\"ad6c42e\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-51f8d95 elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"51f8d95\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"41\" height=\"37\" viewbox=\"0 0 41 37\" fill=\"none\"><g id=\"Group 4\"><path id=\"Vector 1\" d=\"M26.56 21.8427L17.3555 23.8819L34.8878 28.9799L37.956 23.8819L26.56 21.8427Z\" fill=\"#007C90\"><\/path><path id=\"Vector 2\" d=\"M24.5057 16.0031L18.8164 21.7706L25.9645 20.6171L36.3219 22.4915L40.5524 16.0031L35.5925 19.752L24.5057 16.0031Z\" fill=\"#00B7CE\"><\/path><path id=\"Vector 3\" d=\"M6.48828 16.5743L16.8466 21.8425L24.2871 14.8182L31.144 16.5743L19.6186 8.37921L9.11434 11.8914L6.48828 16.5743Z\" fill=\"#FFC415\"><\/path><path id=\"Vector 4\" d=\"M32.6597 29.4075L18.75 25.4114L24.5545 36.1356L32.6597 29.4075Z\" fill=\"#005968\"><\/path><g id=\"Vector 5\"><path d=\"M0 14.4313L2.13447 10.3225L4.72633 12.1487V15.1922L0 14.4313Z\" fill=\"#FFC20D\"><\/path><path d=\"M11.5871 8.64862L7.92804 10.3225L4.72633 6.82252L10.5199 3.93118L11.5871 8.64862Z\" fill=\"#FFC20D\"><\/path><path d=\"M19.9726 5.75729L15.7036 6.82252L12.9593 1.49638L19.9726 0.431152V5.75729Z\" fill=\"#FFC20D\"><\/path><path d=\"M22.8694 6.82252L25.6137 8.64862L29.2728 4.84424L24.8514 2.25726L22.8694 6.82252Z\" fill=\"#FFC20D\"><\/path><path d=\"M31.7122 14.4313L29.2728 11.3878L32.7794 8.64862L35.5237 12.1487L31.7122 14.4313Z\" fill=\"#FFC20D\"><\/path><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"> Pr\u00e9sentons-nous<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5aa5220 elementor-widget elementor-widget-heading\" data-id=\"5aa5220\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">A propos de nous<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-539e06b elementor-absolute elementor-widget elementor-widget-template\" data-id=\"539e06b\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"237\" class=\"elementor elementor-237\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a209a72 e-con-full bread-temp e-flex e-con e-parent\" data-id=\"a209a72\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d74ef5 breadicon elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"4d74ef5\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/dive-greece.gr\/fr\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"45\" height=\"45\" viewbox=\"0 0 45 45\" fill=\"none\"><g id=\"Group 31\"><path id=\"Vector 1\" d=\"M24.5465 28.6369L18.4102 22.5005L24.5465 16.3641\" stroke=\"white\"><\/path><circle id=\"Ellipse 3\" cx=\"22.5\" cy=\"22.5\" r=\"22\" stroke=\"white\"><\/circle><\/g><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-588e45f elementor-align-left bread-yoast elementor-widget elementor-widget-breadcrumbs\" data-id=\"588e45f\" data-element_type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<span id=\"breadcrumbs\"><span><span><a href=\"https:\/\/dive-greece.gr\/fr\/\">Home<\/a><\/span><\/span><\/span>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e4d9b24 e-con-full e-flex e-con e-parent\" data-id=\"e4d9b24\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-fcde370 e-con-full e-flex e-con e-child\" data-id=\"fcde370\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-f67e5d4 elementor-widget elementor-widget-heading\" data-id=\"f67e5d4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Qui sommes - nous<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e5abe0 elementor-widget elementor-widget-text-editor\" data-id=\"6e5abe0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tMembres de PADI, la premi\u00e8re organisation de formation \u00e0 la plong\u00e9e dans le monde, nous sommes situ\u00e9s dans le sud de la p\u00e9ninsule de Kassandra, en Gr\u00e8ce du Nord. Install\u00e9s dans le charmant village de Loutra Agias Paraskevis, \u00e0 seulement quelques centaines de m\u00e8tres d\u2019un magnifique rivage class\u00e9 Natura 2000, nous vous offrons tous les services n\u00e9cessaires pour profiter pleinement de vos plong\u00e9es et de votre formation, tout au long de l\u2019ann\u00e9e !\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9b1a26f elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"9b1a26f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/padi-logo.jpg\" class=\"attachment-full size-full wp-image-2796\" alt=\"PADI logo \u2013 international scuba diving training and certification organization.\" srcset=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/padi-logo.jpg 1200w, https:\/\/dive-greece.gr\/wp-content\/uploads\/padi-logo-768x512.jpg 768w, https:\/\/dive-greece.gr\/wp-content\/uploads\/padi-logo-18x12.jpg 18w, https:\/\/dive-greece.gr\/wp-content\/uploads\/padi-logo-600x400.jpg 600w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b366965 e-con-full e-flex e-con e-parent\" data-id=\"b366965\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-459f001 e-con-full e-flex e-con e-child\" data-id=\"459f001\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d9098d5 elementor-align-left elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"d9098d5\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"41\" height=\"37\" viewbox=\"0 0 41 37\" fill=\"none\"><g id=\"Group 4\"><path id=\"Vector 1\" d=\"M26.56 21.8427L17.3555 23.8819L34.8878 28.9799L37.956 23.8819L26.56 21.8427Z\" fill=\"#007C90\"><\/path><path id=\"Vector 2\" d=\"M24.5057 16.0031L18.8164 21.7706L25.9645 20.6171L36.3219 22.4915L40.5524 16.0031L35.5925 19.752L24.5057 16.0031Z\" fill=\"#00B7CE\"><\/path><path id=\"Vector 3\" d=\"M6.48828 16.5743L16.8466 21.8425L24.2871 14.8182L31.144 16.5743L19.6186 8.37921L9.11434 11.8914L6.48828 16.5743Z\" fill=\"#FFC415\"><\/path><path id=\"Vector 4\" d=\"M32.6597 29.4075L18.75 25.4114L24.5545 36.1356L32.6597 29.4075Z\" fill=\"#005968\"><\/path><g id=\"Vector 5\"><path d=\"M0 14.4313L2.13447 10.3225L4.72633 12.1487V15.1922L0 14.4313Z\" fill=\"#FFC20D\"><\/path><path d=\"M11.5871 8.64862L7.92804 10.3225L4.72633 6.82252L10.5199 3.93118L11.5871 8.64862Z\" fill=\"#FFC20D\"><\/path><path d=\"M19.9726 5.75729L15.7036 6.82252L12.9593 1.49638L19.9726 0.431152V5.75729Z\" fill=\"#FFC20D\"><\/path><path d=\"M22.8694 6.82252L25.6137 8.64862L29.2728 4.84424L24.8514 2.25726L22.8694 6.82252Z\" fill=\"#FFC20D\"><\/path><path d=\"M31.7122 14.4313L29.2728 11.3878L32.7794 8.64862L35.5237 12.1487L31.7122 14.4313Z\" fill=\"#FFC20D\"><\/path><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Plong\u00e9es et Destinations<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c625a06 elementor-widget elementor-widget-heading\" data-id=\"c625a06\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ce que nous vous offrons \n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ffa2042 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"ffa2042\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p class=\"translation-block\">Profitez de la beaut\u00e9 qui se cache sous la surface scintillante de la mer, avec ses paysages magnifiques et son accueil chaleureux.\nNich\u00e9 dans le nord-est de la M\u00e9diterran\u00e9e, la Chalcidique \u2014 avec ses trois p\u00e9ninsules distinctes \u2014 vous invite \u00e0 explorer :<\/p><ul><li class=\"translation-block\">Kassandra \u2013 la mythique, o\u00f9 se situe notre centre de plong\u00e9e<\/li><li class=\"translation-block\">Sithonia, la sauvage<\/li><li class=\"translation-block\">Athos, le sacr\u00e9<\/li><\/ul><p>Rejoignez-nous et associez l\u2019excitation de la plong\u00e9e \u00e0 l\u2019exp\u00e9rience des secrets les mieux gard\u00e9s de la Gr\u00e8ce !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8286984 elementor-widget elementor-widget-heading\" data-id=\"8286984\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pourquoi plonger avec nous :\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8c91bc3 e-con-full e-flex e-con e-child\" data-id=\"8c91bc3\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-616df10 e-con-full level-box e-flex e-con e-child\" data-id=\"616df10\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-28dcff8 elementor-widget__width-initial elementor-absolute icon-hover-boxes elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"28dcff8\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"81\" viewbox=\"0 0 80 81\" fill=\"none\"><rect y=\"0.231689\" width=\"80\" height=\"80\" rx=\"40\" fill=\"white\"><\/rect><g clip-path=\"url(#clip0_1117_5436)\"><path d=\"M64.9669 34.6062C65.3419 33.5182 57.0734 33.5417 46.9534 34.1607C44.4316 24.1949 41.4692 15.4813 40.0068 16.2973C38.3849 15.3922 35.3335 24.073 32.8023 34.1091C22.7104 33.4103 14.531 33.279 15.0513 34.2686C14.3951 36.4259 20.2215 41.9364 28.7337 47.4563C25.3729 56.6717 24.2198 62.4401 24.5854 64.2316C27.3275 63.0264 32.1461 61.0566 39.8943 55.1522C47.6847 60.9066 52.6204 62.5621 55.4329 63.35C55.7047 61.8867 54.4438 56.4044 51.0408 47.3531C59.5718 41.8285 65.5013 36.5009 64.9669 34.6062ZM22.5886 36.6838C22.4995 36.9699 22.237 37.1481 21.9511 37.1481C21.8855 37.1481 21.8152 37.1387 21.7495 37.1153L20.423 36.6932C20.0715 36.5806 19.8793 36.2055 19.9871 35.8537C20.0996 35.502 20.4746 35.3097 20.8261 35.4176L22.1526 35.8396C22.5042 35.9522 22.6964 36.3274 22.5886 36.6791V36.6838ZM28.1665 39.0756C28.1009 39.0756 28.0306 39.0662 27.965 39.0428L26.6384 38.6207C26.2869 38.5081 26.0947 38.133 26.2072 37.7812C26.3197 37.4295 26.69 37.2372 27.0462 37.3498L28.3728 37.7718C28.7243 37.8844 28.9165 38.2596 28.804 38.6113C28.7149 38.8927 28.4524 39.0756 28.1712 39.0756H28.1665ZM29.3759 58.4913L28.6306 59.5559C28.4993 59.7388 28.2931 59.842 28.0821 59.842C27.9509 59.842 27.815 59.8045 27.7025 59.7201C27.4025 59.509 27.3275 59.0916 27.5384 58.7915L28.2837 57.7269C28.4946 57.4268 28.9118 57.3517 29.2118 57.5628C29.5118 57.7738 29.5868 58.1912 29.3759 58.4913ZM33.1632 53.159L32.4179 54.2236C32.2867 54.4112 32.0805 54.5097 31.8695 54.5097C31.7383 54.5097 31.6023 54.4722 31.4899 54.3878C31.1899 54.1767 31.1149 53.7593 31.3258 53.4592L32.0711 52.3946C32.282 52.0945 32.6992 52.0194 32.9992 52.2305C33.2992 52.4415 33.3742 52.8589 33.1632 53.159ZM34.9491 40.6467C34.8601 40.9281 34.5976 41.111 34.3163 41.111C34.2507 41.111 34.1804 41.1016 34.1148 41.0781L32.7882 40.6561C32.4367 40.5435 32.2445 40.1683 32.357 39.8166C32.4695 39.4649 32.8398 39.2679 33.196 39.3851L34.5226 39.8072C34.8741 39.9198 35.0663 40.2949 34.9538 40.6467H34.9491ZM37.0397 47.5313L36.2944 48.5959C36.1631 48.7788 35.9569 48.882 35.746 48.882C35.6147 48.882 35.4788 48.8444 35.3663 48.76C35.0663 48.549 34.9913 48.1316 35.2022 47.8314L35.9475 46.7669C36.1585 46.4667 36.5756 46.3917 36.8756 46.6027C37.1756 46.8138 37.2506 47.2311 37.0397 47.5313ZM39.3318 28.6736C39.3318 28.3078 39.6318 28.0077 39.9974 28.0077C40.363 28.0077 40.663 28.3078 40.663 28.6736V29.9352C40.663 30.301 40.363 30.6012 39.9974 30.6012C39.6318 30.6012 39.3318 30.301 39.3318 29.9352V28.6736ZM40.663 42.8884C40.663 43.2542 40.363 43.5544 39.9974 43.5544C39.6318 43.5544 39.3318 43.2542 39.3318 42.8884V41.8942C39.3318 41.5284 39.6318 41.2282 39.9974 41.2282C40.363 41.2282 40.663 41.5284 40.663 41.8942V42.8884ZM40.663 36.2148C40.663 36.5806 40.363 36.8808 39.9974 36.8808C39.6318 36.8808 39.3318 36.5806 39.3318 36.2148V34.9533C39.3318 34.5875 39.6318 34.2873 39.9974 34.2873C40.363 34.2873 40.663 34.5875 40.663 34.9533V36.2148ZM44.6332 48.5724C44.516 48.6615 44.3754 48.6991 44.2395 48.6991C44.0332 48.6991 43.8317 48.6053 43.7004 48.427L42.9223 47.3625C42.7067 47.067 42.7676 46.6496 43.0676 46.4292C43.3676 46.2088 43.7848 46.2791 44.0004 46.5746L44.7785 47.6392C44.9941 47.9346 44.9332 48.352 44.6332 48.5724ZM45.6269 41.2282C45.341 41.2282 45.0785 41.0453 44.9894 40.7545C44.8816 40.4028 45.0785 40.0276 45.43 39.9245L46.7566 39.5211C47.1081 39.4086 47.4831 39.6102 47.5862 39.962C47.694 40.3137 47.4972 40.6889 47.1456 40.7921L45.8191 41.1954C45.7535 41.2141 45.6878 41.2235 45.6269 41.2235V41.2282ZM48.5049 53.8438C48.3878 53.9329 48.2471 53.9704 48.1112 53.9704C47.905 53.9704 47.7034 53.8766 47.5722 53.6984L46.7941 52.6338C46.5784 52.3383 46.6394 51.9209 46.9394 51.7005C47.2347 51.4801 47.6565 51.5504 47.8722 51.8459L48.6503 52.9105C48.8659 53.2059 48.8049 53.6233 48.5049 53.8438ZM51.6314 57.0609L52.4095 58.1255C52.6251 58.421 52.5642 58.8384 52.2642 59.0588C52.147 59.1479 52.0064 59.1854 51.8705 59.1854C51.6642 59.1854 51.4627 59.0916 51.3314 58.9134L50.5533 57.8488C50.3377 57.5534 50.3986 57.136 50.6986 56.9156C50.9939 56.6951 51.4158 56.7655 51.6314 57.0609ZM53.3798 38.888L52.0533 39.2913C51.9877 39.3101 51.922 39.3195 51.8611 39.3195C51.5752 39.3195 51.3127 39.1366 51.2236 38.8458C51.1158 38.4941 51.3127 38.1189 51.6689 38.011L52.9954 37.6077C53.3517 37.5045 53.722 37.7015 53.8298 38.0532C53.9376 38.405 53.7407 38.7801 53.3845 38.888H53.3798ZM59.6093 36.9324L58.2828 37.3357C58.2171 37.3545 58.1515 37.3638 58.0906 37.3638C57.8047 37.3638 57.5422 37.1809 57.4531 36.8902C57.3453 36.5384 57.5422 36.1632 57.8984 36.0554L59.2249 35.6521C59.5812 35.5442 59.9515 35.7459 60.0593 36.0976C60.1671 36.4493 59.9702 36.8245 59.614 36.9324H59.6093Z\" fill=\"#00B7CE\"><\/path><\/g><defs><clippath id=\"clip0_1117_5436\"><rect width=\"50\" height=\"48\" fill=\"white\" transform=\"translate(15 16.2317)\"><\/rect><\/clippath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c3bb8b1 e-con-full inner-cont-box e-flex e-con e-child\" data-id=\"c3bb8b1\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fbe0d22 box-title elementor-widget elementor-widget-heading\" data-id=\"fbe0d22\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">La passion est au c\u0153ur de ce que nous faisons<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fba248 text-inner-box elementor-widget elementor-widget-text-editor\" data-id=\"7fba248\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tPlus qu\u2019une passion pour la mer et la plong\u00e9e, nous avons \u00e0 c\u0153ur de partager notre expertise avec vous, d'enseigner et de transmettre cette passion.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-735bce9 e-con-full level-box e-flex e-con e-child\" data-id=\"735bce9\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7e4fcc9 elementor-widget__width-initial elementor-absolute icon-hover-boxes elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7e4fcc9\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"81\" viewbox=\"0 0 80 81\" fill=\"none\"><rect y=\"0.231689\" width=\"80\" height=\"80\" rx=\"40\" fill=\"white\"><\/rect><g clip-path=\"url(#clip0_1117_3658)\"><path d=\"M60.9241 52.3516C60.1611 47.5606 51.2999 55.9309 50.0352 52.9769C48.7705 50.0229 56.6157 46.7757 56.3628 43.9985C56.1099 41.2171 53.3234 40.4365 53.0704 38.496C52.8175 36.5554 54.841 30.4275 52.0587 31.29C49.2764 32.1525 50.0352 39.9104 50.5411 41.3421C51.0469 42.7738 51.0469 46.4825 49.0235 46.4393C47 46.3962 48.2014 35.1366 44.85 35.8266C41.3047 36.5554 36.6212 30.7294 38.3917 25.4209C40.1876 20.039 45.7353 22.8291 49.0235 22.3116C52.3158 21.7942 52.2484 18.3098 45.0144 17.3136C39.0241 16.4856 32.9494 22.0529 33.3288 26.9733C33.8979 34.3475 39.1505 36.2923 40.4152 38.496C41.6799 40.6996 42.1858 43.9295 39.9093 44.7748C37.6329 45.62 35.1879 35.6153 32.9915 35.8266C30.7952 36.0379 27.8865 39.2765 25.2264 35.8266C23.5402 33.6359 21.6811 31.6091 19.9105 33.0451C18.14 34.4811 18.8566 39.919 22.95 41.3421C27.3806 42.8816 31.5582 41.0877 33.5817 45.1198C34.5092 46.9611 32.317 48.5998 29.5305 47.953C26.744 47.3061 21.4282 43.3215 19.9105 45.896C18.3929 48.4705 24.788 51.1441 27.2541 51.7435C32.9494 53.1321 31.6847 57.6644 33.3288 63.2317H45.4781C45.4781 60.7607 46.7597 56.72 50.5411 57.4057C59.5287 59.0314 61.4342 55.5384 60.9241 52.3559V52.3516Z\" fill=\"#00B7CE\"><\/path><\/g><defs><clippath id=\"clip0_1117_3658\"><rect width=\"42\" height=\"46\" fill=\"white\" transform=\"translate(19 17.2317)\"><\/rect><\/clippath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7357f6f e-con-full inner-cont-box e-flex e-con e-child\" data-id=\"7357f6f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fd2733e box-title elementor-widget elementor-widget-heading\" data-id=\"fd2733e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Flexibilit\u00e9 adapt\u00e9e \u00e0 vos besoins<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7aae9fe text-inner-box elementor-widget elementor-widget-text-editor\" data-id=\"7aae9fe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNous ne croyons pas en une approche \u00ab taille unique \u00bb. Nous prenons le temps d\u2019\u00e9couter vos pr\u00e9f\u00e9rences afin de vous proposer une exp\u00e9rience parfaitement adapt\u00e9e \u00e0 votre emploi du temps, \u00e0 votre rythme d\u2019apprentissage et \u00e0 vos centres d\u2019int\u00e9r\u00eat en plong\u00e9e.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7b29bf2 e-con-full level-box e-flex e-con e-child\" data-id=\"7b29bf2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-48f5754 elementor-widget__width-initial elementor-absolute icon-hover-boxes elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"48f5754\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"81\" viewbox=\"0 0 80 81\" fill=\"none\"><rect y=\"0.231689\" width=\"80\" height=\"80\" rx=\"40\" fill=\"white\"><\/rect><g clip-path=\"url(#clip0_1117_7275)\"><path d=\"M40.0022 17.2317C31.7161 17.2317 25 23.9389 25 32.2141C25 32.2319 25 32.2497 25 32.2674C25.1201 32.143 25.2357 32.0187 25.3514 31.8943C26.3966 30.7661 27.384 29.7045 28.7939 29.7045C30.2795 29.7045 31.1023 30.7394 31.8317 31.65C32.4455 32.4184 32.9748 33.0803 33.7932 33.0803C35.1898 33.0803 36.0437 32.2541 36.9466 31.3835C37.8006 30.5573 38.6812 29.7 40.0022 29.7C41.3232 29.7 42.2039 30.5529 43.0578 31.3835C43.9607 32.2585 44.8102 33.0803 46.2113 33.0803C47.0297 33.0803 47.5589 32.4184 48.1727 31.6456C48.9021 30.735 49.725 29.7 51.2105 29.7C52.6961 29.7 53.6079 30.7661 54.6531 31.8899C54.7687 32.0142 54.8844 32.1386 55.0044 32.263C55.0044 32.2452 55.0044 32.2274 55.0044 32.2052C55 23.9389 48.2839 17.2317 40.0022 17.2317Z\" fill=\"#00B7CE\"><\/path><path d=\"M51.2061 35.8298C51.6953 35.8298 52.1312 36.0075 52.5537 36.2873C52.5938 36.314 52.6294 36.3317 52.6694 36.3584C52.7717 36.4294 52.8784 36.4783 52.9852 36.5183C53.0208 36.5316 53.0563 36.5361 53.0919 36.5405C53.1675 36.5583 53.2431 36.5716 53.3188 36.576C53.3543 36.576 53.3899 36.576 53.4255 36.576C53.5278 36.5716 53.6257 36.5538 53.7191 36.5272C53.7457 36.5183 53.7769 36.5138 53.8036 36.505C53.9192 36.4605 54.0304 36.4028 54.1327 36.3228C54.1549 36.3051 54.1727 36.2873 54.1905 36.2695C54.2706 36.2029 54.3373 36.1274 54.3996 36.0386C54.4218 36.0075 54.444 35.9808 54.4618 35.9497C54.5285 35.8342 54.5864 35.7143 54.6219 35.5766C54.6976 35.2568 54.7509 34.9325 54.8043 34.6038C54.8488 34.3062 54.8844 34.0042 54.9155 33.6977C54.7821 33.6844 54.6486 33.6311 54.5508 33.5334C54.2839 33.2668 54.0259 32.987 53.7724 32.716C52.8695 31.7433 52.0912 30.9082 51.2061 30.9082C50.321 30.9082 49.7472 31.6011 49.1067 32.4051C48.404 33.289 47.6034 34.2885 46.2068 34.2885C44.321 34.2885 43.1557 33.1602 42.2216 32.2541C41.4789 31.5345 40.834 30.9082 40.0022 30.9082C39.1705 30.9082 38.5256 31.5301 37.7784 32.2541C36.8443 33.1602 35.679 34.2885 33.7932 34.2885C32.3966 34.2885 31.6004 33.289 30.8933 32.4051C30.2528 31.6011 29.7013 30.9082 28.7939 30.9082C27.8866 30.9082 27.1305 31.7477 26.2276 32.716C25.9741 32.987 25.7205 33.2624 25.4492 33.5334C25.3514 33.6311 25.2179 33.6844 25.0845 33.6977H25.089C25.1201 34.0042 25.1557 34.3062 25.2001 34.6038C25.2535 34.9325 25.3069 35.2568 25.3825 35.5766C25.4136 35.7143 25.4715 35.8387 25.5426 35.9497C25.5604 35.9808 25.5827 36.0119 25.6049 36.0386C25.6672 36.123 25.7383 36.2029 25.8139 36.2695C25.8362 36.2873 25.854 36.3051 25.8718 36.3228C25.9741 36.3984 26.0852 36.4605 26.2009 36.505C26.2276 36.5138 26.2543 36.5183 26.2854 36.5272C26.3832 36.5538 26.4811 36.5716 26.5789 36.576C26.6145 36.576 26.6501 36.5805 26.6901 36.576C26.7658 36.576 26.8414 36.5583 26.9125 36.5405C26.9481 36.5316 26.9837 36.5272 27.0193 36.5138C27.126 36.4783 27.2372 36.425 27.3351 36.3539C27.4329 36.2829 27.5352 36.2207 27.6375 36.1629C27.6864 36.1318 27.7398 36.1096 27.7932 36.083C27.8421 36.0608 27.891 36.0341 27.94 36.0164C28.0067 35.9853 28.0778 35.9631 28.1446 35.9408C28.1757 35.932 28.2068 35.9231 28.238 35.9142C28.318 35.892 28.3981 35.8698 28.4826 35.8564C28.5849 35.8387 28.6916 35.8254 28.7984 35.8254C29.4344 35.8254 29.9236 36.0741 30.3506 36.4339C30.9555 36.9447 31.4314 37.6821 31.9785 38.2684C32.0541 38.3483 32.1297 38.4283 32.2098 38.5038C32.2543 38.5438 32.2943 38.5838 32.3388 38.6193C32.4589 38.7215 32.5834 38.8192 32.7168 38.8991C32.7346 38.9125 32.7569 38.9169 32.7791 38.9302C32.8992 38.9968 33.0282 39.0546 33.1616 39.099C33.2016 39.1123 33.2461 39.1257 33.2906 39.139C33.4507 39.179 33.6197 39.2101 33.8021 39.2101C34.0067 39.2101 34.1979 39.1923 34.3803 39.1656C34.4203 39.1612 34.4603 39.1479 34.5004 39.139C34.6427 39.1123 34.785 39.0812 34.9185 39.0413C34.9496 39.0324 34.9763 39.0191 35.0074 39.0102C35.1497 38.9613 35.2876 38.908 35.4166 38.8458C35.4299 38.8414 35.4433 38.8325 35.4566 38.8236C35.6034 38.7525 35.7457 38.6726 35.8792 38.5882C36.6664 38.0952 37.2847 37.3933 37.9251 36.8203C37.9607 36.7892 37.9963 36.7581 38.0274 36.7271C38.0852 36.6738 38.1475 36.6249 38.2053 36.576C38.2632 36.5272 38.3254 36.4828 38.3877 36.4383C38.45 36.3939 38.5078 36.3495 38.5701 36.3095C38.6457 36.2562 38.7213 36.2074 38.8013 36.1629C38.8414 36.1407 38.8814 36.123 38.9259 36.1007C38.997 36.0652 39.0682 36.0341 39.1394 36.003C39.1838 35.9853 39.2239 35.9675 39.2683 35.9542C39.3484 35.9275 39.4285 35.9053 39.5085 35.8875C39.5486 35.8787 39.5886 35.8698 39.6286 35.8609C39.7532 35.8387 39.8777 35.8254 40.0111 35.8254C40.1446 35.8254 40.2691 35.8387 40.3936 35.8609C40.4337 35.8698 40.4737 35.8787 40.5137 35.8875C40.5938 35.9053 40.6738 35.9275 40.7539 35.9542C40.7984 35.9675 40.8428 35.9853 40.8829 36.003C40.954 36.0341 41.0252 36.0652 41.0964 36.1007C41.1364 36.123 41.1764 36.1407 41.2209 36.1629C41.301 36.2074 41.3766 36.2562 41.4522 36.3095C41.5145 36.3495 41.5723 36.3939 41.6301 36.4383C41.6924 36.4828 41.7546 36.5316 41.8125 36.5805C41.8703 36.6293 41.9325 36.6782 41.9904 36.7315C42.0259 36.7626 42.0615 36.7937 42.0971 36.8248C42.1683 36.8914 42.2439 36.958 42.3151 37.0247C42.8799 37.5577 43.4448 38.1529 44.1431 38.5926C44.2765 38.677 44.4188 38.757 44.5656 38.8281C44.579 38.8325 44.5923 38.8414 44.6056 38.8503C44.7391 38.9125 44.8769 38.9658 45.0148 39.0146C45.046 39.0235 45.0726 39.0368 45.1038 39.0457C45.2372 39.0857 45.3795 39.1168 45.5219 39.1434C45.5619 39.1523 45.6019 39.1612 45.642 39.1701C45.8243 39.1967 46.02 39.2145 46.2202 39.2145C46.4025 39.2145 46.5715 39.1834 46.7317 39.1434C46.7761 39.1301 46.8162 39.1212 46.8606 39.1079C46.9941 39.0635 47.1231 39.0102 47.2431 38.9391C47.2609 38.9258 47.2832 38.9213 47.3054 38.908C47.4388 38.8281 47.5634 38.7303 47.6835 38.6282C47.7279 38.5926 47.768 38.5527 47.8125 38.5127C47.8925 38.4372 47.9681 38.3617 48.0437 38.2773C48.5908 37.6909 49.0623 36.9536 49.6716 36.4428C50.0986 36.083 50.5878 35.8342 51.2239 35.8342L51.2061 35.8298Z\" fill=\"#00B7CE\"><\/path><path d=\"M31.0178 48.4314C31.0178 47.0944 30.3284 46.2016 29.7191 45.4109C29.1364 44.6602 28.6383 44.0073 28.6383 42.9412C28.6383 42.4482 28.9274 42.1373 29.4789 41.582C30.0615 41.0001 30.831 40.2184 30.9867 38.9658C30.7865 38.7392 30.5997 38.5127 30.4262 38.295C29.7235 37.4111 29.3543 37.0247 28.7984 37.0247C28.6738 37.0247 28.4737 37.0602 28.1712 37.2423C28.5493 37.722 28.7717 38.1129 28.7717 38.5171C28.7717 39.0812 28.4692 39.4144 27.8866 39.9963C27.255 40.627 26.3877 41.4932 26.3877 42.9412C26.3877 44.7757 27.2461 45.8862 27.9355 46.7834C28.4648 47.4719 28.7672 47.8895 28.7672 48.4314C28.7672 48.9733 28.4648 49.3908 27.9355 50.0793C27.2461 50.9721 26.3877 52.087 26.3877 53.9215C26.3877 55.3651 27.2506 56.2313 27.8821 56.8665C28.4648 57.4484 28.7672 57.7771 28.7672 58.3456C28.7672 58.9142 28.3358 59.4517 27.6286 60.2734C27.3128 60.6421 26.9837 61.0241 26.6723 61.4638C26.3165 61.9702 26.4366 62.672 26.9437 63.0274C27.1394 63.1651 27.3662 63.2317 27.593 63.2317C27.9444 63.2317 28.2913 63.0673 28.5137 62.7564C28.7628 62.4055 29.0563 62.0635 29.341 61.7303C30.1282 60.8153 31.0178 59.7759 31.0178 58.3456C31.0178 56.8265 30.1282 55.9337 29.4789 55.2807C28.9274 54.73 28.6383 54.4146 28.6383 53.9215C28.6383 52.851 29.1408 52.2025 29.7191 51.4474C30.3284 50.6568 31.0178 49.7639 31.0178 48.4269V48.4314Z\" fill=\"#00B7CE\"><\/path><path d=\"M53.6123 42.9412C53.6123 41.4976 52.7494 40.6315 52.1134 39.9963C51.5308 39.4144 51.2283 39.0857 51.2283 38.5171C51.2283 38.1129 51.4552 37.722 51.8288 37.2423C51.5308 37.0558 51.3262 37.0247 51.2016 37.0247C50.6412 37.0247 50.2765 37.4111 49.5738 38.295C49.4003 38.5127 49.2135 38.7437 49.0133 38.9658C49.169 40.2139 49.9385 40.9957 50.5211 41.582C51.0726 42.1328 51.3618 42.4482 51.3618 42.9412C51.3618 44.0117 50.8592 44.6602 50.281 45.4109C49.6716 46.2016 48.9822 47.0944 48.9822 48.4314C48.9822 49.7684 49.6716 50.6612 50.281 51.4519C50.8636 52.207 51.3618 52.8555 51.3618 53.926C51.3618 54.419 51.0726 54.7299 50.5211 55.2852C49.8718 55.9381 48.9822 56.8265 48.9822 58.3501C48.9822 59.7804 49.8718 60.8198 50.659 61.7348C50.9437 62.0635 51.2372 62.4099 51.4863 62.7608C51.7042 63.0718 52.0511 63.2361 52.407 63.2361C52.6294 63.2361 52.8562 63.1695 53.0563 63.0318C53.5634 62.672 53.6835 61.9746 53.3277 61.4683C53.0163 61.0285 52.6916 60.6465 52.3714 60.2778C51.6642 59.4561 51.2328 58.9231 51.2328 58.3501C51.2328 57.7771 51.5352 57.4528 52.1179 56.8709C52.7494 56.2402 53.6123 55.374 53.6123 53.926C53.6123 52.0915 52.7539 50.9766 52.0645 50.0838C51.5308 49.3953 51.2328 48.9777 51.2328 48.4358C51.2328 47.8939 51.5352 47.4764 52.0645 46.7879C52.7539 45.8951 53.6123 44.7802 53.6123 42.9457V42.9412Z\" fill=\"#00B7CE\"><\/path><path d=\"M38.1253 38.5216C38.1253 38.4416 38.1119 38.3661 38.1075 38.2862C37.2624 39.1035 36.2305 40.0496 34.6783 40.325C34.109 40.9246 33.4952 41.7286 33.4952 42.9457C33.4952 44.7802 34.3536 45.8906 35.043 46.7879C35.5723 47.4764 35.8747 47.8939 35.8747 48.4358C35.8747 48.9777 35.5723 49.3953 35.043 50.0838C34.3536 50.9766 33.4952 52.0915 33.4952 53.926C33.4952 55.3696 34.358 56.2357 34.9896 56.8709C35.5723 57.4528 35.8747 57.7815 35.8747 58.3501C35.8747 58.9186 35.4433 59.4561 34.7361 60.2778C34.4203 60.6465 34.0912 61.0285 33.7798 61.4683C33.4196 61.9746 33.5441 62.6765 34.0511 63.0318C34.2469 63.1695 34.4737 63.2361 34.7005 63.2361C35.0519 63.2361 35.3988 63.0718 35.6212 62.7609C35.8703 62.4099 36.1638 62.0679 36.4485 61.7348C37.2357 60.8198 38.1253 59.7804 38.1253 58.3501C38.1253 56.831 37.2357 55.9381 36.5864 55.2852C36.0348 54.7344 35.7457 54.419 35.7457 53.926C35.7457 52.8555 36.2483 52.207 36.8265 51.4519C37.4359 50.6612 38.1253 49.7684 38.1253 48.4314C38.1253 47.0944 37.4359 46.2016 36.8265 45.4109C36.2483 44.6602 35.7457 44.0073 35.7457 42.9412C35.7457 42.4482 36.0348 42.1373 36.5864 41.582C37.2357 40.9291 38.1253 40.0407 38.1253 38.5171V38.5216Z\" fill=\"#00B7CE\"><\/path><path d=\"M46.5004 42.9412C46.5004 41.7286 45.891 40.9246 45.3173 40.3205C43.765 40.0496 42.7376 39.1035 41.8881 38.2817C41.8836 38.3617 41.8703 38.4372 41.8703 38.5171C41.8703 40.0362 42.7598 40.9291 43.4092 41.582C43.9607 42.1328 44.2498 42.4482 44.2498 42.9412C44.2498 44.0117 43.7472 44.6602 43.169 45.4109C42.5597 46.2016 41.8703 47.0944 41.8703 48.4314C41.8703 49.7684 42.5597 50.6612 43.169 51.4519C43.7517 52.207 44.2498 52.8555 44.2498 53.926C44.2498 54.419 43.9607 54.73 43.4092 55.2852C42.7598 55.9381 41.8703 56.8265 41.8703 58.3501C41.8703 59.7804 42.7598 60.8198 43.5471 61.7348C43.8317 62.0635 44.1253 62.4099 44.3744 62.7609C44.5923 63.0718 44.9392 63.2361 45.295 63.2361C45.5174 63.2361 45.7443 63.1695 45.9444 63.0318C46.4514 62.672 46.5715 61.9746 46.2157 61.4683C45.9044 61.0285 45.5797 60.6465 45.2595 60.2778C44.5523 59.4561 44.1208 58.9231 44.1208 58.3501C44.1208 57.7771 44.4233 57.4528 45.0059 56.8709C45.6375 56.2402 46.5004 55.374 46.5004 53.926C46.5004 52.0915 45.642 50.9766 44.9526 50.0838C44.4188 49.3953 44.1208 48.9777 44.1208 48.4358C44.1208 47.8939 44.4233 47.4764 44.9526 46.7879C45.642 45.8951 46.5004 44.7802 46.5004 42.9457V42.9412Z\" fill=\"#00B7CE\"><\/path><\/g><defs><clippath id=\"clip0_1117_7275\"><rect width=\"30\" height=\"46\" fill=\"white\" transform=\"translate(25 17.2317)\"><\/rect><\/clippath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9a5ff15 e-con-full inner-cont-box e-flex e-con e-child\" data-id=\"9a5ff15\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1acccd9 box-title elementor-widget elementor-widget-heading\" data-id=\"1acccd9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Engagement pour la protection de l\u2019environnement marin<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9f67843 text-inner-box elementor-widget elementor-widget-text-editor\" data-id=\"9f67843\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tIl ne pourrait en \u00eatre autrement. Nos sites de plong\u00e9e sont situ\u00e9s dans des zones class\u00e9es Natura 2000, ce qui renforce notre responsabilit\u00e9 en mati\u00e8re de protection et de pr\u00e9servation de l\u2019\u00e9cosyst\u00e8me marin.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-d2b0af6 e-con-full level-box e-flex e-con e-child\" data-id=\"d2b0af6\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bf157bd elementor-widget__width-initial elementor-absolute icon-hover-boxes elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"bf157bd\" data-element_type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"80\" height=\"81\" viewbox=\"0 0 80 81\" fill=\"none\"><rect y=\"0.231689\" width=\"80\" height=\"80\" rx=\"40\" fill=\"white\"><\/rect><g clip-path=\"url(#clip0_1117_3452)\"><path d=\"M45.4831 38.9894C39.7014 38.9894 34.9994 34.3079 34.9994 28.5515C34.9994 28.2995 35.0191 28.0514 35.0389 27.8034C34.4774 27.7246 33.9079 27.6813 33.3266 27.6813C26.5167 27.6774 21 33.1739 21 39.9502C21 46.7264 26.5167 52.219 33.3226 52.219C40.1285 52.219 45.6452 46.7264 45.6452 39.9502C45.6452 39.6155 45.6334 39.3005 45.6136 38.9855C45.5701 38.9855 45.5266 38.9934 45.4831 38.9934V38.9894Z\" fill=\"#00B7CE\"><\/path><path d=\"M54.1081 32.1778C54.5827 31.0635 54.8437 29.839 54.8437 28.5515C54.8437 23.4053 50.6518 19.2317 45.4831 19.2317C45.1667 19.2317 44.8503 19.2474 44.5419 19.2789C44.4312 19.2908 44.3204 19.3144 44.2137 19.3262C44.0199 19.3537 43.8221 19.3774 43.6323 19.4128C43.4939 19.4404 43.3634 19.4797 43.225 19.5152C43.0668 19.5546 42.9086 19.59 42.7544 19.6372C42.6041 19.6845 42.4578 19.7396 42.3115 19.7947C42.181 19.842 42.0465 19.8853 41.916 19.9404C41.7539 20.0074 41.5996 20.0822 41.4454 20.157C41.3347 20.2082 41.224 20.2593 41.1172 20.3145C40.9511 20.4011 40.7889 20.4995 40.6268 20.598C40.5398 20.6491 40.4489 20.7003 40.3658 20.7555C40.1958 20.8696 40.0297 20.9878 39.8636 21.1138C39.7963 21.1649 39.7291 21.2122 39.6619 21.2634C39.4879 21.4012 39.3218 21.5469 39.1596 21.6965C39.1122 21.7398 39.0608 21.7831 39.0133 21.8264C38.8433 21.9918 38.6772 22.1611 38.519 22.3383C38.4874 22.3737 38.4518 22.4092 38.4241 22.4446C38.258 22.6336 38.0998 22.8344 37.9495 23.0352C37.9298 23.0628 37.91 23.0864 37.8902 23.1139C37.736 23.3305 37.5897 23.5549 37.4512 23.7833C37.4433 23.799 37.4315 23.8148 37.4236 23.8305C37.2812 24.0707 37.1507 24.3148 37.0321 24.5708C37.0321 24.5786 37.0241 24.5865 37.0202 24.5944C36.8976 24.8543 36.7869 25.122 36.688 25.3937C36.3874 26.2205 36.2055 27.1064 36.1541 28.0239C36.1462 28.1971 36.1264 28.3703 36.1264 28.5475C36.1264 33.6937 40.3183 37.8673 45.487 37.8673C47.7491 37.8673 49.8213 37.068 51.4388 35.7411C51.6681 35.5521 51.8935 35.3513 52.1031 35.1387C52.9494 34.2961 53.6336 33.2921 54.1081 32.1778ZM45.4831 23.7754C42.8374 23.7754 40.6861 25.9174 40.6861 28.5515C40.6861 29.3232 40.8641 30.0595 41.216 30.7367C41.3584 31.0123 41.2516 31.3509 40.9748 31.4927C40.8918 31.536 40.8048 31.5557 40.7178 31.5557C40.5121 31.5557 40.3183 31.4454 40.2155 31.2525C39.7845 30.4257 39.5591 29.4886 39.5591 28.5515C39.5591 25.2992 42.2166 22.6533 45.4831 22.6533C45.7915 22.6533 46.0446 22.9053 46.0446 23.2124C46.0446 23.5195 45.7915 23.7715 45.4831 23.7715V23.7754Z\" fill=\"#00B7CE\"><\/path><path d=\"M53.6415 50.5575C50.6795 50.5575 48.283 52.9475 48.283 55.8926C48.283 58.8378 50.6834 61.2278 53.6415 61.2278C56.5995 61.2278 59 58.8378 59 55.8926C59 52.9475 56.5995 50.5575 53.6415 50.5575Z\" fill=\"#00B7CE\"><\/path><\/g><defs><clippath id=\"clip0_1117_3452\"><rect width=\"38\" height=\"42\" fill=\"white\" transform=\"translate(21 19.2317)\"><\/rect><\/clippath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bc3b4ba e-con-full inner-cont-box e-flex e-con e-child\" data-id=\"bc3b4ba\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b0ec8d6 box-title elementor-widget elementor-widget-heading\" data-id=\"b0ec8d6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Un accueil chaleureux et familial<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5755e4b text-inner-box elementor-widget elementor-widget-text-editor\" data-id=\"5755e4b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tNous sommes un centre de plong\u00e9e familial. D\u00e8s le premier contact, vous \u00eates accueillis comme des invit\u00e9s, dans le respect de l\u2019une des plus anciennes valeurs de la Gr\u00e8ce : l\u2019hospitalit\u00e9.\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca29680 e-con-full e-flex e-con e-child\" data-id=\"ca29680\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-d698ce8 e-con-full e-flex e-con e-child\" data-id=\"d698ce8\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d556459 elementor-widget__width-initial elementor-widget-tablet__width-inherit katadush-change-color-mobile elementor-widget elementor-widget-heading\" data-id=\"d556459\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">D\u00e9couvrez nos installations<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8c41571 e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"8c41571\" data-element_type=\"container\">\n\t\t<a class=\"elementor-element elementor-element-e3516d7 e-con-full icon-container-left swiper-button-prev-emepeiria-katadyshs e-flex e-con e-child\" data-id=\"e3516d7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"#\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78e2582 firsticon-left elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"78e2582\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\"><polygon points=\"12.718 4.707 11.305 3.292 2.585 12 11.305 20.707 12.718 19.292 6.417 13 20 13 20 11 6.416 11 12.718 4.707\"><\/polygon><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-989a920 secondicon-left elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"989a920\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\"><polygon points=\"12.718 4.707 11.305 3.292 2.585 12 11.305 20.707 12.718 19.292 6.417 13 20 13 20 11 6.416 11 12.718 4.707\"><\/polygon><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-176e9be e-con-full icon-container-right swiper-button-next-emepeiria-katadyshs e-flex e-con e-child\" data-id=\"176e9be\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"#\">\n\t\t\t\t<div class=\"elementor-element elementor-element-691f93c firsticon-right elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"691f93c\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\"><polygon points=\"11.293 4.707 17.586 11 4 11 4 13 17.586 13 11.293 19.293 12.707 20.707 21.414 12 12.707 3.293 11.293 4.707\"><\/polygon><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e516393 secondicon-right elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"e516393\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\"><polygon points=\"11.293 4.707 17.586 11 4 11 4 13 17.586 13 11.293 19.293 12.707 20.707 21.414 12 12.707 3.293 11.293 4.707\"><\/polygon><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5fa7c9a e-con-full slider-emepeiria-katadyshs e-flex e-con e-child\" data-id=\"5fa7c9a\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b134481 e-con-full swiper-container e-flex e-con e-child\" data-id=\"b134481\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-ed04ca0 e-con-full swiper-wrapper e-flex e-con e-child\" data-id=\"ed04ca0\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-0e3ca0a elementor-widget__width-inherit swiper-slide  elementor-widget elementor-widget-image\" data-id=\"0e3ca0a\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/elementor\/thumbs\/dive-greece-office-entrance-halkidiki-rdxclgjc652zfw5an0u0kr4qezylqvjzyw2a996ta6.jpg\" title=\"dive-greece-office-entrance-halkidiki\" alt=\"Entrance to Dive Greece PADI Dive Center in Halkidiki, Greece, with official signage and flags. Your starting point for scuba adventures.\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c34bb04 elementor-widget__width-inherit swiper-slide  elementor-widget elementor-widget-image\" data-id=\"c34bb04\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/elementor\/thumbs\/dive-greece-scuba-diving-center-halkidiki-rdxclumx0nmaa1ktcoxf45knbs13yc3z0tukgelwou.jpg\" title=\"dive-greece-scuba-diving-center-halkidiki\" alt=\"Exterior view of Dive Greece&#039;s scuba diving center in Halkidiki, featuring shop entrance, PADI signage, and outdoor setup.\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-af1215c elementor-widget__width-inherit swiper-slide  elementor-widget elementor-widget-image\" data-id=\"af1215c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/elementor\/thumbs\/test-retuxeabjwj1p55nps99vwm5jd05befd8mb6ujqu9q.jpg\" title=\"test\" alt=\"scuba-dive\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c02df4a elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-html\" data-id=\"c02df4a\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n\n\n\n\n<\/style>\n\n<script>\ndocument.addEventListener(\"DOMContentLoaded\", function () {\n    var mySwiper = new Swiper(\".slider-emepeiria-katadyshs .swiper-container\", {\n        centeredSlides: false,\n        loop: false,\n         navigation: {\n            nextEl: \".swiper-button-next-emepeiria-katadyshs\",\n            prevEl: \".swiper-button-prev-emepeiria-katadyshs\",\n        },\n       \n        slidesPerView: 1.15,\n        spaceBetween: 10,\n        slidesPerGroup: 1,\n        speed: 400,\n        breakpoints: {\n            768: {\n            \n                slidesPerView: 2.2,\n                slidesPerGroup: 1,\n                spaceBetween: 20,\n            },\n                 1150: {\n            \n                slidesPerView: 2.85,\n                slidesPerGroup: 1,\n                spaceBetween: 20,\n            },\n        },\n \n    });\n\n\n});\n\n\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e838452 e-con-full e-flex e-con e-parent\" data-id=\"e838452\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36e5e6f iconlist-drasthriothtes elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"36e5e6f\" data-element_type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"41\" height=\"37\" viewbox=\"0 0 41 37\" fill=\"none\"><g id=\"Group 4\"><path id=\"Vector 1\" d=\"M26.56 21.8427L17.3555 23.8819L34.8878 28.9799L37.956 23.8819L26.56 21.8427Z\" fill=\"#007C90\"><\/path><path id=\"Vector 2\" d=\"M24.5057 16.0031L18.8164 21.7706L25.9645 20.6171L36.3219 22.4915L40.5524 16.0031L35.5925 19.752L24.5057 16.0031Z\" fill=\"#00B7CE\"><\/path><path id=\"Vector 3\" d=\"M6.48828 16.5743L16.8466 21.8425L24.2871 14.8182L31.144 16.5743L19.6186 8.37921L9.11434 11.8914L6.48828 16.5743Z\" fill=\"#FFC415\"><\/path><path id=\"Vector 4\" d=\"M32.6597 29.4075L18.75 25.4114L24.5545 36.1356L32.6597 29.4075Z\" fill=\"#005968\"><\/path><g id=\"Vector 5\"><path d=\"M0 14.4313L2.13447 10.3225L4.72633 12.1487V15.1922L0 14.4313Z\" fill=\"#FFC20D\"><\/path><path d=\"M11.5871 8.64862L7.92804 10.3225L4.72633 6.82252L10.5199 3.93118L11.5871 8.64862Z\" fill=\"#FFC20D\"><\/path><path d=\"M19.9726 5.75729L15.7036 6.82252L12.9593 1.49638L19.9726 0.431152V5.75729Z\" fill=\"#FFC20D\"><\/path><path d=\"M22.8694 6.82252L25.6137 8.64862L29.2728 4.84424L24.8514 2.25726L22.8694 6.82252Z\" fill=\"#FFC20D\"><\/path><path d=\"M31.7122 14.4313L29.2728 11.3878L32.7794 8.64862L35.5237 12.1487L31.7122 14.4313Z\" fill=\"#FFC20D\"><\/path><\/g><\/g><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Qui sommes-nous? <\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7033bab elementor-widget elementor-widget-heading\" data-id=\"7033bab\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Notre \u00e9quipe<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ba5d745 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"ba5d745\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Notre \u00e9quipe r\u00e9unit des professionnels PADI passionn\u00e9s par la plong\u00e9e bouteille et la mer. Gr\u00e2ce \u00e0 leur exp\u00e9rience, leurs comp\u00e9tences sp\u00e9cialis\u00e9es et leur engagement envers la s\u00e9curit\u00e9 et le plaisir de nos h\u00f4tes, nous offrons des exp\u00e9riences sous-marines uniques, aussi bien aux plongeurs d\u00e9butants qu\u2019aux plongeurs chevronn\u00e9s.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0269c56 e-con-full e-flex e-con e-child\" data-id=\"0269c56\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e437786 elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"e437786\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/emilios-seretakis-padi-instructor-dive-greece-1.jpg\" class=\"attachment-large size-large wp-image-2407\" alt=\"Emilios Seretakis, PADI instructor, helping a student during open water scuba training in Halkidiki, Greece. Dive Greece team.\" srcset=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/emilios-seretakis-padi-instructor-dive-greece-1.jpg 1920w, https:\/\/dive-greece.gr\/wp-content\/uploads\/emilios-seretakis-padi-instructor-dive-greece-1-768x512.jpg 768w, https:\/\/dive-greece.gr\/wp-content\/uploads\/emilios-seretakis-padi-instructor-dive-greece-1-1536x1024.jpg 1536w, https:\/\/dive-greece.gr\/wp-content\/uploads\/emilios-seretakis-padi-instructor-dive-greece-1-18x12.jpg 18w, https:\/\/dive-greece.gr\/wp-content\/uploads\/emilios-seretakis-padi-instructor-dive-greece-1-600x400.jpg 600w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-61f2e90 e-con-full e-flex e-con e-child\" data-id=\"61f2e90\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-dc28cd3 elementor-widget elementor-widget-heading\" data-id=\"dc28cd3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Emilios Seretakis<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e82b6f2 elementor-widget elementor-widget-heading\" data-id=\"e82b6f2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Responsable d'activit\u00e9 - Moniteur PADI niveau  Master Scuba Diver Trainer<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5b7e45b elementor-widget elementor-widget-text-editor\" data-id=\"5b7e45b\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\tApr\u00e8s avoir travaill\u00e9 en comptabilit\u00e9 pendant pr\u00e8s de dix ans (DESS en finance, DEA en \u00e9conomie), Emilios s\u2019est tourn\u00e9 vers la formation des adultes lorsqu\u2019il a compris que son altruisme et ses comp\u00e9tences p\u00e9dagogiques trouvaient un terrain d\u2019expression id\u00e9al \u00e0 travers sa passion pour la plong\u00e9e. Ayant grandi pr\u00e8s de la mer et poss\u00e9dant une connaissance approfondie de l\u2019environnement marin de la Chalcidique, il est l\u00e0 pour vous accueillir et s\u2019assurer que vous tiriez le meilleur de chaque plong\u00e9e. Attentif et d\u00e9vou\u00e9, il se remet constamment en question afin de faire de Dive Greece une exp\u00e9rience transformatrice et inoubliable pour chaque plongeur.\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1d22be7 e-con-full e-flex e-con e-child\" data-id=\"1d22be7\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-787fa59 e-con-full e-flex e-con e-child\" data-id=\"787fa59\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-16827c5 elementor-widget elementor-widget-heading\" data-id=\"16827c5\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Anastasia Deligianni<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f628a0 elementor-widget elementor-widget-heading\" data-id=\"6f628a0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default\">Responsable des r\u00e9servations<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64792c3 elementor-widget elementor-widget-text-editor\" data-id=\"64792c3\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Gr\u00e2ce \u00e0 son sens pratique et \u00e0 sa solide exp\u00e9rience dans les ventes, Anastasia se distingue par sa capacit\u00e9 \u00e0 comprendre vos attentes et \u00e0 vous proposer les solutions les plus adapt\u00e9es. Elle est souvent votre premier contact chez Dive Greece: son accueil chaleureux et son sourire vous font imm\u00e9diatement sentir comme chez vous.\nQu\u2019elle organise vos plong\u00e9es ou vous aide \u00e0 planifier l\u2019ensemble de votre s\u00e9jour en Chalcidique, Anastasia met tout en \u0153uvre pour vous guider avec clart\u00e9, efficacit\u00e9 et bienveillance. Sa parfaite connaissance de la r\u00e9gion et son sens du service font d\u2019elle une interlocutrice privil\u00e9gi\u00e9e pour transformer votre s\u00e9jour en une exp\u00e9rience m\u00e9morable.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-46a4bbc elementor-widget__width-initial elementor-widget-mobile__width-inherit elementor-widget elementor-widget-image\" data-id=\"46a4bbc\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/dive-greece-anastasia-deligianni-scaled.jpg\" class=\"attachment-large size-large wp-image-2570\" alt=\"Selfie \u03c4\u03b7\u03c2 \u0391\u03bd\u03b1\u03c3\u03c4\u03b1\u03c3\u03af\u03b1\u03c2 \u0394\u03b5\u03bb\u03b7\u03b3\u03b9\u03ac\u03bd\u03bd\u03b7, \u03bc\u03ad\u03bb\u03bf\u03c2 \u03c4\u03b7\u03c2 \u03bf\u03bc\u03ac\u03b4\u03b1\u03c2 \u03c4\u03b7\u03c2 Dive Greece, \u03bc\u03b5 \u03c6\u03c9\u03c4\u03b5\u03b9\u03bd\u03cc \u03ba\u03b1\u03b9 \u03c6\u03b9\u03bb\u03b9\u03ba\u03cc \u03c7\u03b1\u03bc\u03cc\u03b3\u03b5\u03bb\u03bf.\" srcset=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/dive-greece-anastasia-deligianni-scaled.jpg 2560w, https:\/\/dive-greece.gr\/wp-content\/uploads\/dive-greece-anastasia-deligianni-768x576.jpg 768w, https:\/\/dive-greece.gr\/wp-content\/uploads\/dive-greece-anastasia-deligianni-1536x1152.jpg 1536w, https:\/\/dive-greece.gr\/wp-content\/uploads\/dive-greece-anastasia-deligianni-2048x1536.jpg 2048w, https:\/\/dive-greece.gr\/wp-content\/uploads\/dive-greece-anastasia-deligianni-16x12.jpg 16w, https:\/\/dive-greece.gr\/wp-content\/uploads\/dive-greece-anastasia-deligianni-600x450.jpg 600w\" sizes=\"(max-width: 2560px) 100vw, 2560px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e1c5021 e-con-full e-flex e-con e-parent\" data-id=\"e1c5021\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5583162 elementor-widget__width-inherit swiper-slide  elementor-widget elementor-widget-template\" data-id=\"5583162\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"922\" class=\"elementor elementor-922\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26702ac6 e-con-full e-flex e-con e-child\" data-id=\"26702ac6\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2f7e3e6 pistopoihseis-title elementor-widget elementor-widget-heading\" data-id=\"2f7e3e6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Nos certifications\n\n<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1f2b9f5 e-con-full e-flex e-con e-child\" data-id=\"1f2b9f5\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ca69594 elementor-widget__width-initial pistopoihseis-text elementor-widget elementor-widget-text-editor\" data-id=\"ca69594\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Que ce soit dans les bons moments ou dans les moments plus difficiles, nous continuons \u00e0 apprendre et \u00e0 nous perfectionner afin de vous offrir des services s\u00fbrs et de haute qualit\u00e9. Votre confiance est notre r\u00e9compense la plus pr\u00e9cieuse, et nos prix en sont la preuve. Un grand merci !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-db6e12a e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"db6e12a\" data-element_type=\"container\">\n\t\t<a class=\"elementor-element elementor-element-963c4d2 e-con-full icon-container-left swiper-button-prev-slider-pistopoihseis e-flex e-con e-child\" data-id=\"963c4d2\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"#\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e367ac firsticon-left elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"2e367ac\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\"><polygon points=\"12.718 4.707 11.305 3.292 2.585 12 11.305 20.707 12.718 19.292 6.417 13 20 13 20 11 6.416 11 12.718 4.707\"><\/polygon><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dffb5ac secondicon-left elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"dffb5ac\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\"><polygon points=\"12.718 4.707 11.305 3.292 2.585 12 11.305 20.707 12.718 19.292 6.417 13 20 13 20 11 6.416 11 12.718 4.707\"><\/polygon><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-c3a398a e-con-full icon-container-right swiper-button-next-slider-pistopoihseis e-flex e-con e-child\" data-id=\"c3a398a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"#\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c6a21c9 firsticon-right elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"c6a21c9\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\"><polygon points=\"11.293 4.707 17.586 11 4 11 4 13 17.586 13 11.293 19.293 12.707 20.707 21.414 12 12.707 3.293 11.293 4.707\"><\/polygon><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-db032db secondicon-right elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"db032db\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\"><polygon points=\"11.293 4.707 17.586 11 4 11 4 13 17.586 13 11.293 19.293 12.707 20.707 21.414 12 12.707 3.293 11.293 4.707\"><\/polygon><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e9fb624 e-con-full slider-pistopoihseis e-flex e-con e-child\" data-id=\"e9fb624\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-70fbe06b e-con-full swiper-container e-flex e-con e-child\" data-id=\"70fbe06b\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-1779d19f e-con-full swiper-wrapper e-flex e-con e-child\" data-id=\"1779d19f\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e121fb1 elementor-widget__width-inherit swiper-slide  elementor-widget elementor-widget-image\" data-id=\"e121fb1\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/dive-greece-padi-excellence-certificate-2019.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ2NCwidXJsIjoiaHR0cHM6XC9cL2RpdmUtZ3JlZWNlLmdyXC93cC1jb250ZW50XC91cGxvYWRzXC9kaXZlLWdyZWVjZS1wYWRpLWV4Y2VsbGVuY2UtY2VydGlmaWNhdGUtMjAxOS5qcGcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/elementor\/thumbs\/dive-greece-padi-excellence-certificate-2019-reb8j9hzo6pxq9by3o8fw2j7cb2neblb3r2vzvnxz2.jpg\" title=\"dive-greece-padi-excellence-certificate-2019\" alt=\"Certificate of Excellence awarded to Emilios Seretakis (MSDT 285671) by PADI for outstanding customer service and professionalism in scuba diving instruction \u2013 29 August 2019. Dive Greece.\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5dbf0f3 elementor-widget__width-inherit swiper-slide  elementor-widget elementor-widget-image\" data-id=\"5dbf0f3\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/padi-excellence-certificate-dive-greece-august-2019.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ2NywidXJsIjoiaHR0cHM6XC9cL2RpdmUtZ3JlZWNlLmdyXC93cC1jb250ZW50XC91cGxvYWRzXC9wYWRpLWV4Y2VsbGVuY2UtY2VydGlmaWNhdGUtZGl2ZS1ncmVlY2UtYXVndXN0LTIwMTkuanBnIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/elementor\/thumbs\/padi-excellence-certificate-dive-greece-august-2019-reb8o67nd1fucy79fsmawtxv0qvnlf2ug1q67wdxha.jpg\" title=\"padi-excellence-certificate-dive-greece-august-2019\" alt=\"padi-excellence-certificate-dive-greece-august-2019\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-54e9e6c elementor-widget__width-inherit swiper-slide  elementor-widget elementor-widget-image\" data-id=\"54e9e6c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/covid-instruction_page-0001-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ3MCwidXJsIjoiaHR0cHM6XC9cL2RpdmUtZ3JlZWNlLmdyXC93cC1jb250ZW50XC91cGxvYWRzXC9jb3ZpZC1pbnN0cnVjdGlvbl9wYWdlLTAwMDEtc2NhbGVkLmpwZyJ9\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/elementor\/thumbs\/covid-instruction_page-0001-scaled-reb8oeo72jrf9fuz2e9y19t0d7pyip0fh7ljje1dxa.jpg\" title=\"covid instruction_page-0001\" alt=\"covid instruction_page-0001\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-793d7ce elementor-widget__width-inherit swiper-slide  elementor-widget elementor-widget-image\" data-id=\"793d7ce\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/covid-management_page-0001-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ3MSwidXJsIjoiaHR0cHM6XC9cL2RpdmUtZ3JlZWNlLmdyXC93cC1jb250ZW50XC91cGxvYWRzXC9jb3ZpZC1tYW5hZ2VtZW50X3BhZ2UtMDAwMS1zY2FsZWQuanBnIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/elementor\/thumbs\/covid-management_page-0001-scaled-reb8ogjvg7tzwns8rf3769bxjzgoy37w5gwihxylku.jpg\" title=\"covid management_page-0001\" alt=\"covid management_page-0001\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8212e63 elementor-widget__width-inherit swiper-slide  elementor-widget elementor-widget-image\" data-id=\"8212e63\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/dive-greece-padi-excellence-certificate-2022-1-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ3MiwidXJsIjoiaHR0cHM6XC9cL2RpdmUtZ3JlZWNlLmdyXC93cC1jb250ZW50XC91cGxvYWRzXC9kaXZlLWdyZWVjZS1wYWRpLWV4Y2VsbGVuY2UtY2VydGlmaWNhdGUtMjAyMi0xLXNjYWxlZC5qcGcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/elementor\/thumbs\/dive-greece-padi-excellence-certificate-2022-1-scaled-reb8oifjtvwkjvpigfwgb8uuqr7fdhfctq7hghvt8e.jpg\" title=\"dive-greece-padi-excellence-certificate-2022\" alt=\"dive-greece-padi-excellence-certificate-2022\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-956d317 elementor-widget__width-inherit swiper-slide  elementor-widget elementor-widget-image\" data-id=\"956d317\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/dive-greece-padi-excellence-certificate-2022-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ2NSwidXJsIjoiaHR0cHM6XC9cL2RpdmUtZ3JlZWNlLmdyXC93cC1jb250ZW50XC91cGxvYWRzXC9kaXZlLWdyZWVjZS1wYWRpLWV4Y2VsbGVuY2UtY2VydGlmaWNhdGUtMjAyMi1zY2FsZWQuanBnIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/elementor\/thumbs\/dive-greece-padi-excellence-certificate-2022-scaled-reb8lcp2uxkvj2apwkqlfjk2v4s0i3vu239qe0kg5a.jpg\" title=\"dive-greece-padi-excellence-certificate-2022\" alt=\"dive-greece-padi-excellence-certificate-2022\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1dffc4e elementor-widget__width-inherit swiper-slide  elementor-widget elementor-widget-image\" data-id=\"1dffc4e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/elite-padi-instructor-award-2022-dive-greece-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ3MywidXJsIjoiaHR0cHM6XC9cL2RpdmUtZ3JlZWNlLmdyXC93cC1jb250ZW50XC91cGxvYWRzXC9lbGl0ZS1wYWRpLWluc3RydWN0b3ItYXdhcmQtMjAyMi1kaXZlLWdyZWVjZS1zY2FsZWQuanBnIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/elementor\/thumbs\/elite-padi-instructor-award-2022-dive-greece-scaled-reb8okb87jz573ms5gppg8drxiy5svmthzigf1t0vy.jpg\" title=\"elite-padi-instructor-award-2022-dive-greece\" alt=\"elite-padi-instructor-award-2022-dive-greece\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31fa60b elementor-widget__width-inherit swiper-slide  elementor-widget elementor-widget-image\" data-id=\"31fa60b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/elite-padi-instructor-award-2023-dive-greece.png\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ3NCwidXJsIjoiaHR0cHM6XC9cL2RpdmUtZ3JlZWNlLmdyXC93cC1jb250ZW50XC91cGxvYWRzXC9lbGl0ZS1wYWRpLWluc3RydWN0b3ItYXdhcmQtMjAyMy1kaXZlLWdyZWVjZS5wbmcifQ%3D%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/elementor\/thumbs\/elite-padi-instructor-award-2023-dive-greece-reb8on4qs2305xioozxl5po5pok9fyy0idgwuvouda.png\" title=\"elite-padi-instructor-award-2023-dive-greece\" alt=\"elite-padi-instructor-award-2023-dive-greece\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3c25278 elementor-widget__width-inherit swiper-slide  elementor-widget elementor-widget-image\" data-id=\"3c25278\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/elite-padi-instructor-award-2024-dive-greece-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ3NSwidXJsIjoiaHR0cHM6XC9cL2RpdmUtZ3JlZWNlLmdyXC93cC1jb250ZW50XC91cGxvYWRzXC9lbGl0ZS1wYWRpLWluc3RydWN0b3ItYXdhcmQtMjAyNC1kaXZlLWdyZWVjZS1zY2FsZWQuanBnIn0%3D\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/elementor\/thumbs\/elite-padi-instructor-award-2024-dive-greece-scaled-reb8op0f5q5kt5fye0quap72wgazvd5h6mrvtfm20u.jpg\" title=\"elite-padi-instructor-award-2024-dive-greece\" alt=\"elite-padi-instructor-award-2024-dive-greece\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e8f5a5f elementor-widget__width-inherit swiper-slide  elementor-widget elementor-widget-image\" data-id=\"e8f5a5f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/Certificate-GR006324-SERETAKIS-13289-e_certificate_page-0001-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ2OSwidXJsIjoiaHR0cHM6XC9cL2RpdmUtZ3JlZWNlLmdyXC93cC1jb250ZW50XC91cGxvYWRzXC9DZXJ0aWZpY2F0ZS1HUjAwNjMyNC1TRVJFVEFLSVMtMTMyODktZV9jZXJ0aWZpY2F0ZV9wYWdlLTAwMDEtc2NhbGVkLmpwZyJ9\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/elementor\/thumbs\/Certificate-GR006324-SERETAKIS-13289-e_certificate_page-0001-scaled-reb8oawub7m9z00focnfrar5zo8hnwli4ozlma6ym6.jpg\" title=\"Certificate GR006324 SERETAKIS 13289 e_certificate_page-0001\" alt=\"Certificate GR006324 SERETAKIS 13289 e_certificate_page-0001\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ea7b068 elementor-widget__width-inherit swiper-slide  elementor-widget elementor-widget-image\" data-id=\"ea7b068\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/Certificate-GR006323-SERETAKIS-14467-e_certificate_page-0001-scaled.jpg\" data-elementor-open-lightbox=\"yes\" data-e-action-hash=\"#elementor-action%3Aaction%3Dlightbox%26settings%3DeyJpZCI6MjQ2OCwidXJsIjoiaHR0cHM6XC9cL2RpdmUtZ3JlZWNlLmdyXC93cC1jb250ZW50XC91cGxvYWRzXC9DZXJ0aWZpY2F0ZS1HUjAwNjMyMy1TRVJFVEFLSVMtMTQ0NjctZV9jZXJ0aWZpY2F0ZV9wYWdlLTAwMDEtc2NhbGVkLmpwZyJ9\">\n\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/elementor\/thumbs\/Certificate-GR006323-SERETAKIS-14467-e_certificate_page-0001-scaled-reb8o83bqpif064j4tfk1tgs7ime0tab4b156gb54u.jpg\" title=\"Certificate GR006323 SERETAKIS 14467 e_certificate_page-0001\" alt=\"Certificate GR006323 SERETAKIS 14467 e_certificate_page-0001\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55c68717 elementor-widget elementor-widget-html\" data-id=\"55c68717\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n<script>\ndocument.addEventListener(\"DOMContentLoaded\", function () {\n    var mySwiper = new Swiper(\".slider-pistopoihseis .swiper-container\", {\n        centeredSlides: false,\n        loop: false,\n         navigation: {\n            nextEl: \".swiper-button-next-slider-pistopoihseis\",\n            prevEl: \".swiper-button-prev-slider-pistopoihseis\",\n        },\n       \n        slidesPerView: 2,\n        spaceBetween: 20,\n        slidesPerGroup: 1,\n        speed: 400,\n        breakpoints: {\n            768: {\n            \n                slidesPerView: 3.6,\n                slidesPerGroup: 1,\n                spaceBetween: 20,\n            },\n                 1250: {\n            \n                slidesPerView: 5.3,\n                slidesPerGroup: 1,\n                spaceBetween: 20,\n            },\n        },\n \n    });\n\n\n});\n\n\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e5fd5a8 e-con-full e-flex e-con e-parent\" data-id=\"e5fd5a8\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9d257c2 elementor-widget elementor-widget-template\" data-id=\"9d257c2\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"437\" class=\"elementor elementor-437\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db3e1c7 e-con-full e-flex e-con e-parent\" data-id=\"db3e1c7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-19eb52e elementor-widget elementor-widget-heading\" data-id=\"19eb52e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Pourquoi nous choisir<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-20b8c3c e-con-full e-flex e-con e-child\" data-id=\"20b8c3c\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-804cd97 e-con-full e-flex e-con e-child\" data-id=\"804cd97\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ba5d923 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"ba5d923\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"96\" height=\"96\" viewbox=\"0 0 96 96\" fill=\"none\"><rect width=\"96\" height=\"96\" rx=\"48\" fill=\"#EBF0F8\"><\/rect><g clip-path=\"url(#clip0_946_6104)\"><path d=\"M45.98 66.8842C41.7152 62.6515 30.0063 50.1739 26.7504 37.96C24.3264 38.4106 22.5 40.5533 22.5 43.0747C22.5 44.2155 22.8681 45.3037 23.5614 46.2192C23.5949 46.2672 23.6283 46.3199 23.6475 46.3726C29.7386 56.1707 39.0665 62.9056 44.101 66.0502C44.6891 66.4193 45.3202 66.6973 45.98 66.8842Z\" fill=\"#00B7CE\"><\/path><path d=\"M42.6656 28.1422C41.8815 27.6916 41.0066 27.4424 40.0982 27.4424C37.851 27.4424 35.8525 28.9236 35.1641 31.0567C37.4638 41.6073 43.3971 55.8058 46.567 62.9914C45.2713 54.1568 42.7517 36.018 42.6704 28.1422H42.6656Z\" fill=\"#00B7CE\"><\/path><path d=\"M62.1428 31.6279C59.6471 42.84 53.2213 57.9349 50.2188 64.6699C55.1528 59.5647 65.3653 47.9691 68.0379 37.0686V37.0494C68.0475 36.9584 68.0523 36.8721 68.0523 36.781C68.0523 33.6748 65.3414 31.1677 62.138 31.6279H62.1428Z\" fill=\"#00B7CE\"><\/path><path d=\"M27.9462 36.781C27.9462 36.8769 27.9557 36.9727 27.9605 37.0686C30.6332 47.9691 40.8504 59.5647 45.7797 64.6699C42.7772 57.9349 36.3514 42.8352 33.8556 31.6279C30.6523 31.1677 27.9414 33.6748 27.9414 36.781H27.9462Z\" fill=\"#00B7CE\"><\/path><path d=\"M54.7185 65.887C53.9679 66.3904 53.2699 66.8457 52.6388 67.2388C51.2522 68.1065 49.6553 68.5618 48.0202 68.5618H47.9676C46.3373 68.5618 44.7404 68.1065 43.3539 67.2388C42.7227 66.8457 42.0247 66.3904 41.2741 65.887C39.07 65.6617 35.2786 65.5659 34.4419 67.4401C33.2657 70.0814 47.9915 69.9999 47.9915 69.9999C47.9915 69.9999 62.7173 70.0814 61.5412 67.4401C60.7092 65.5707 56.9131 65.6617 54.709 65.887H54.7185Z\" fill=\"#00B7CE\"><\/path><path d=\"M72.3521 46.3727C72.3712 46.32 72.4046 46.2721 72.4381 46.2241C73.1314 45.3086 73.4995 44.2204 73.4995 43.0796C73.4995 40.5582 71.6731 38.4154 69.2491 37.9648C65.9932 50.1788 54.2843 62.6564 50.0195 66.8891C50.6793 66.7022 51.3104 66.4242 51.8985 66.055C56.9282 62.9105 66.2609 56.1755 72.3521 46.3775V46.3727Z\" fill=\"#00B7CE\"><\/path><path d=\"M51.9378 27.9797C50.9721 26.7574 49.5473 26.0336 47.9839 26C46.4491 26.0336 45.0244 26.7574 44.0586 27.9797C44.1112 35.6878 46.7217 54.4066 47.9982 63.1356C49.2748 54.4066 51.8853 35.683 51.9378 27.9797Z\" fill=\"#00B7CE\"><\/path><path d=\"M55.9015 27.4473C54.9931 27.4473 54.1134 27.6965 53.3341 28.1471C53.248 36.0277 50.7284 54.1665 49.4375 62.9962C52.6074 55.8107 58.5359 41.6122 60.8404 31.0616C60.1519 28.9285 58.1534 27.4473 55.9063 27.4473H55.9015Z\" fill=\"#00B7CE\"><\/path><\/g><defs><clippath id=\"clip0_946_6104\"><rect width=\"51\" height=\"44\" fill=\"white\" transform=\"translate(22.5 26)\"><\/rect><\/clippath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-131ab05 elementor-widget elementor-widget-heading\" data-id=\"131ab05\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default translation-block\">Approche <br>personalis\u00e9e<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-be2fee2 elementor-widget elementor-widget-text-editor\" data-id=\"be2fee2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chaque plongeur est unique pour nous.\nNous adaptons notre approche \u00e0 vos besoins, \u00e0 votre planning et \u00e0 votre rythme d'apprentissage personnel, afin que vous vous sentiez en s\u00e9curit\u00e9, confiant et que vous puissiez appr\u00e9cier chaque instant.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7cc7f9a e-con-full e-flex e-con e-child\" data-id=\"7cc7f9a\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e60d9d elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"2e60d9d\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"96\" height=\"96\" viewbox=\"0 0 96 96\" fill=\"none\"><rect width=\"96\" height=\"96\" rx=\"48\" fill=\"#EBF0F8\"><\/rect><g clip-path=\"url(#clip0_971_6120)\"><path d=\"M50.0347 56.012L54.0396 49.165L47.1523 53.1465L50.0347 56.012Z\" fill=\"#00B7CE\"><\/path><path d=\"M59.3904 55.9713C58.9402 55.9713 58.5719 55.6051 58.5719 55.1576C58.5719 54.7101 58.9402 54.3439 59.3904 54.3439H65.2018C64.7809 45.5557 57.6832 38.4937 48.8374 38.0752V43.8526C48.8374 44.3002 48.4691 44.6664 48.0189 44.6664C47.5687 44.6664 47.2004 44.3002 47.2004 43.8526V38.0752C38.3604 38.4937 31.2569 45.5498 30.8359 54.3439H36.6474C37.0976 54.3439 37.4659 54.7101 37.4659 55.1576C37.4659 55.6051 37.0976 55.9713 36.6474 55.9713H30.8359C31.2569 64.7596 38.3546 71.8215 47.2004 72.24V66.4626C47.2004 66.015 47.5687 65.6488 48.0189 65.6488C48.4691 65.6488 48.8374 66.015 48.8374 66.4626V72.24C57.6774 71.8215 64.7809 64.7654 65.2018 55.9713H59.3904ZM57.0167 47.3226L50.9188 57.7441C50.9188 57.7441 50.8778 57.779 50.8661 57.7964C50.8369 57.8313 50.8252 57.8778 50.7901 57.9068C50.7551 57.9417 50.7141 57.9591 50.6732 57.9824C50.6557 57.994 50.644 58.0231 50.6206 58.0347L40.1378 64.0969C40.0091 64.1725 39.863 64.2074 39.7285 64.2074C39.518 64.2074 39.3076 64.126 39.1497 63.9691C38.8866 63.7075 38.834 63.3007 39.0211 62.9868L45.1132 52.5653C45.1132 52.5653 45.1482 52.5304 45.1658 52.513C45.195 52.4781 45.2067 52.4316 45.2418 52.3967C45.2769 52.3619 45.3178 52.3503 45.3587 52.3212C45.3763 52.3096 45.3879 52.2805 45.4113 52.2689L55.8942 46.2124C56.2157 46.0264 56.6191 46.0788 56.8822 46.3403C57.1453 46.6019 57.1979 47.0087 57.0108 47.3284L57.0167 47.3226Z\" fill=\"#00B7CE\"><\/path><path d=\"M41.9922 61.1448L48.8794 57.1633L45.9971 54.2979L41.9922 61.1448Z\" fill=\"#00B7CE\"><\/path><path d=\"M48.0183 31.3154C30.3617 31.3154 18.7388 49.694 26.3978 65.4977C30.2799 73.5012 38.506 78.9997 48.0183 78.9997C61.2607 78.9997 72.0007 68.3283 72.0007 55.1576C72.0007 41.9868 61.2607 31.3154 48.0183 31.3154ZM48.0183 73.9081C37.6173 73.9081 29.1574 65.4977 29.1574 55.1576C29.1574 44.8174 37.6173 36.407 48.0183 36.407C58.4192 36.407 66.8792 44.8174 66.8792 55.1576C66.8792 65.4977 58.4192 73.9081 48.0183 73.9081Z\" fill=\"#00B7CE\"><\/path><path d=\"M47.0957 27.5493V29.7057C47.4056 29.6941 47.7096 29.6824 48.0195 29.6824C48.3293 29.6824 48.6334 29.6941 48.9432 29.7057V27.5493C51.4572 27.1134 53.3749 24.9396 53.3749 22.3182C53.3749 19.383 50.972 16.9941 48.0195 16.9941C45.067 16.9941 42.6641 19.383 42.6641 22.3182C42.6641 24.9396 44.5817 27.1076 47.0957 27.5435V27.5493ZM48.0195 18.8308C49.9547 18.8308 51.5274 20.3943 51.5274 22.3182C51.5274 24.2421 49.9547 25.8056 48.0195 25.8056C46.0843 25.8056 44.5116 24.2421 44.5116 22.3182C44.5116 20.3943 46.0843 18.8308 48.0195 18.8308Z\" fill=\"#00B7CE\"><\/path><\/g><defs><clippath id=\"clip0_971_6120\"><rect width=\"48\" height=\"62\" fill=\"white\" transform=\"translate(24 17)\"><\/rect><\/clippath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29c084f elementor-widget elementor-widget-heading\" data-id=\"29c084f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default translation-block\">Des moniteurs <br> multingues<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f7abd1e elementor-widget elementor-widget-text-editor\" data-id=\"f7abd1e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nos moniteurs parlent fran\u00e7ais, anglais et grec. Ils sont toujours disponibles pour r\u00e9pondre \u00e0 vos questions et \u00e9changer avec vous, assurant ainsi une communication claire et un soutien \u00e0 chaque \u00e9tape.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a1ac54 e-con-full e-flex e-con e-child\" data-id=\"7a1ac54\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-14d3213 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"14d3213\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"96\" height=\"96\" viewbox=\"0 0 96 96\" fill=\"none\"><rect width=\"96\" height=\"96\" rx=\"48\" fill=\"#EBF0F8\"><\/rect><g clip-path=\"url(#clip0_971_6133)\"><path d=\"M55.0732 37.8398H53.4531V43.4486H55.0732V37.8398Z\" fill=\"#00B7CE\"><\/path><path d=\"M40.0126 43.4428H51.9199V37.834H40.0126C38.4195 37.834 37.1289 39.0932 37.1289 40.6358C37.1289 42.1783 38.4249 43.4375 40.0126 43.4375V43.4428Z\" fill=\"#00B7CE\"><\/path><path d=\"M81.9648 32V39.718L84.0007 40.2584V32H81.9648Z\" fill=\"#00B7CE\"><\/path><path d=\"M65.5762 35.3527L80.4319 39.3087V32C76.2522 32 69.8639 32 69.5615 32C66.6238 32 65.7436 34.1774 65.4844 35.3474C65.5168 35.3474 65.5438 35.3474 65.5762 35.3527Z\" fill=\"#00B7CE\"><\/path><path d=\"M32.5159 43.4957C33.0451 43.4957 33.4771 43.0759 33.4771 42.5617V41.5754H33.8713C33.9847 41.5754 34.0928 41.5491 34.19 41.5124C34.4546 41.8324 34.8542 42.0423 35.3078 42.0423H35.8424C35.6858 41.6016 35.5832 41.1346 35.5832 40.6414C35.5832 40.1482 35.6858 39.6813 35.8424 39.2405H35.3078C34.8542 39.2405 34.4492 39.4504 34.19 39.7705C34.0874 39.7337 33.9847 39.7075 33.8713 39.7075H33.4771V39.1986C33.4771 38.6844 33.0451 38.2646 32.5159 38.2646C31.9867 38.2646 31.5547 38.6844 31.5547 39.1986V42.5617C31.5547 43.0759 31.9867 43.4957 32.5159 43.4957Z\" fill=\"#00B7CE\"><\/path><path d=\"M19.2447 49.1783C18.5211 48.2969 18.0297 47.237 17.846 46.0723L15.875 46.7229L17.0198 49.9129L19.2393 49.1783H19.2447Z\" fill=\"#00B7CE\"><\/path><path d=\"M65.1711 36.7903C65.1171 36.7745 65.0739 36.743 65.0253 36.7168L60.3865 45.2638L55.2078 46.9113C54.1494 47.247 53.0424 47.4202 51.9299 47.4202H30.8856C30.0486 49.5556 28.0991 51.1611 25.7285 51.5651L21.4462 58.0606C21.2032 58.4279 20.8305 58.6902 20.3985 58.8004L13.3352 60.6001C12.2875 60.8676 11.7259 61.9695 12.1417 62.9401C12.4657 63.6904 13.2758 64.1206 14.102 63.979L23.0824 62.4049C23.401 62.3472 23.698 62.2108 23.941 62.0009L30.567 56.3292H52.7993C54.3708 56.3292 55.8936 55.836 57.1573 54.9283L62.3522 51.1769C63.173 50.584 63.8588 49.8337 64.361 48.968L70.5928 38.2384L65.1819 36.7955L65.1711 36.7903Z\" fill=\"#00B7CE\"><\/path><path d=\"M29.7947 45.0803C29.7947 42.2681 27.4403 39.9805 24.5458 39.9805C21.6513 39.9805 19.2969 42.2681 19.2969 45.0803C19.2969 47.8926 21.6513 50.1802 24.5458 50.1802C27.4403 50.1802 29.7947 47.8926 29.7947 45.0803Z\" fill=\"#00B7CE\"><\/path><\/g><defs><clippath id=\"clip0_971_6133\"><rect width=\"72\" height=\"32\" fill=\"white\" transform=\"translate(12 32)\"><\/rect><\/clippath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8a7afdc elementor-widget elementor-widget-heading\" data-id=\"8a7afdc\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default translation-block\">Une \u00e9quipe de formation exp\u00e9riment\u00e9e<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd3cb2c elementor-widget elementor-widget-text-editor\" data-id=\"fd3cb2c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nos moniteurs travaillent ensemble depuis plusieurs ann\u00e9es, formant ainsi une \u00e9quipe solide et coh\u00e9rente. Leur exp\u00e9rience, tant commune qu\u2019individuelle, garantit une formation de qualit\u00e9, avec une priorit\u00e9 absolue sur la s\u00e9curit\u00e9 et le confort.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9926c9d e-con-full e-flex e-con e-child\" data-id=\"9926c9d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7344c02 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"7344c02\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"96\" height=\"96\" viewbox=\"0 0 96 96\" fill=\"none\"><rect width=\"96\" height=\"96\" rx=\"48\" fill=\"#EBF0F8\"><\/rect><g clip-path=\"url(#clip0_971_6149)\"><path d=\"M35.1423 45.7486C35.1085 45.6929 35.0973 45.6316 35.0804 45.5703C32.6055 46.3225 30.3049 47.3533 28.2406 48.4899C28.2012 48.5122 28.1675 48.5345 28.1281 48.5512C27.6781 48.8019 27.2394 49.0526 26.8119 49.3089C26.6994 49.3758 26.5869 49.4482 26.4744 49.5151C26.1313 49.7268 25.7938 49.9385 25.4676 50.1503C25.3438 50.2338 25.2201 50.3118 25.0963 50.3954C24.787 50.6016 24.4889 50.8021 24.202 51.0027C24.0839 51.0863 23.9714 51.1643 23.8533 51.2479C23.5608 51.454 23.2795 51.6602 23.0095 51.8608C22.9139 51.9332 22.8183 52.0001 22.7283 52.0725C22.4189 52.3065 22.1208 52.5349 21.8396 52.7578C21.8002 52.7912 21.7552 52.8191 21.7158 52.8525C21.0633 53.3707 20.4896 53.8554 20.0002 54.29C19.9328 54.3457 19.8765 54.4015 19.8146 54.4572C19.6459 54.6076 19.4828 54.7525 19.3365 54.8862C19.269 54.9475 19.2128 55.0032 19.1509 55.0589C19.0215 55.1759 18.9034 55.2929 18.7965 55.3932C18.7459 55.4434 18.6953 55.4935 18.6447 55.5381C18.549 55.6328 18.459 55.722 18.3803 55.7944C18.3466 55.8278 18.3128 55.8613 18.2847 55.8891C18.2116 55.9615 18.1497 56.0228 18.1047 56.0674C18.0934 56.0785 18.0766 56.1008 18.0653 56.1064C18.0203 56.151 17.9922 56.1844 17.9922 56.1844C17.9922 56.1844 18.0766 56.2736 18.2003 56.3961C18.2397 56.4351 18.2678 56.4686 18.3241 56.5187C18.3747 56.5689 18.4478 56.6357 18.504 56.697C18.5772 56.7694 18.639 56.8307 18.729 56.9143C18.8022 56.9867 18.9034 57.0759 18.9878 57.1539C19.0834 57.243 19.179 57.3322 19.2859 57.4325C19.3871 57.5272 19.5109 57.6331 19.6234 57.7333C19.7415 57.8448 19.8596 57.9451 19.9946 58.0621C20.1184 58.1735 20.259 58.2905 20.394 58.4075C20.5402 58.5301 20.6809 58.6527 20.8383 58.7864C20.9846 58.909 21.1477 59.0371 21.3052 59.1653C21.474 59.3046 21.6371 59.4383 21.8171 59.5776C21.9858 59.7113 22.1658 59.845 22.3402 59.9843C22.5314 60.1292 22.717 60.274 22.9195 60.4245C23.1052 60.5638 23.302 60.7031 23.4989 60.8479C23.707 60.9984 23.9151 61.1544 24.1345 61.3048C24.3426 61.4497 24.5564 61.5945 24.7757 61.7394C25.0007 61.8954 25.2313 62.0458 25.4676 62.2019C25.6926 62.3467 25.9232 62.4916 26.1538 62.6364C26.4013 62.7925 26.6488 62.9429 26.9019 63.0989C27.1382 63.2438 27.3913 63.3831 27.6331 63.5223C27.8975 63.6728 28.1619 63.8232 28.4319 63.9737C28.685 64.1129 28.9493 64.2467 29.2137 64.3804C29.495 64.5253 29.7762 64.6701 30.0631 64.8094C30.3331 64.9376 30.603 65.0601 30.8787 65.1883C31.1768 65.322 31.4749 65.4557 31.7786 65.5839C32.0599 65.7009 32.3411 65.8123 32.628 65.9238C32.9373 66.0463 33.2523 66.1689 33.5673 66.2803C33.8598 66.3862 34.1523 66.4809 34.4504 66.5812C34.6529 66.6481 34.8554 66.7094 35.0579 66.7707C35.0748 66.7205 35.0804 66.6648 35.1085 66.6146C41.0821 56.1064 35.2042 45.8433 35.1479 45.7375L35.1423 45.7486ZM29.7199 56.2568C28.1281 56.2568 26.8344 54.9754 26.8344 53.3986C26.8344 51.8218 28.1281 50.5403 29.7199 50.5403C31.3118 50.5403 32.6111 51.8218 32.6111 53.3986C32.6111 54.9754 31.3118 56.2568 29.7199 56.2568Z\" fill=\"#00B7CE\"><\/path><path d=\"M29.7178 52.123C29.009 52.123 28.4297 52.6969 28.4297 53.399C28.4297 54.101 29.009 54.6749 29.7178 54.6749C30.4265 54.6749 31.0059 54.1066 31.0059 53.399C31.0059 52.6914 30.4265 52.123 29.7178 52.123Z\" fill=\"#00B7CE\"><\/path><path d=\"M67.5875 56.0897C67.5368 56.0395 67.4693 55.9671 67.3737 55.8724C67.3737 55.8724 67.3681 55.8668 67.3625 55.8612C67.2725 55.7721 67.1544 55.6551 67.025 55.5325C67.0081 55.5158 66.9969 55.5046 66.98 55.4879C66.8394 55.3542 66.6762 55.1982 66.4906 55.031C66.4794 55.0199 66.4681 55.0087 66.4569 55.0032C66.2713 54.836 66.0688 54.6466 65.8494 54.4516C65.8382 54.446 65.8325 54.4349 65.8213 54.4293C65.5907 54.2287 65.3432 54.0114 65.0732 53.783C65.0563 53.7663 65.0338 53.7495 65.0169 53.7328C64.4769 53.2759 63.8582 52.7745 63.172 52.2508C63.1439 52.2285 63.1157 52.2117 63.0932 52.1895C62.4014 51.6657 61.6477 51.1141 60.8264 50.5681C60.7983 50.5458 60.7646 50.5291 60.7364 50.5068C59.9096 49.9552 59.0265 49.398 58.0815 48.8632C58.0478 48.8464 58.014 48.8242 57.9803 48.8074C57.5078 48.54 57.024 48.2726 56.5234 48.0163C56.5066 48.0107 56.4897 47.9995 56.4784 47.994C55.9835 47.7377 55.4828 47.4925 54.9654 47.2585C54.9429 47.2474 54.9204 47.2362 54.8979 47.2251C54.3804 46.9855 53.8516 46.7626 53.3117 46.5453C53.261 46.523 53.2104 46.5063 53.1598 46.484C52.6198 46.2723 52.0742 46.0662 51.5173 45.8767C48.8174 44.9685 45.8925 44.3779 42.8439 44.3779C40.7008 44.3779 38.6253 44.6677 36.6453 45.1524C37.4834 46.679 42.4839 56.6635 36.6172 67.2164C36.8366 67.2721 37.0503 67.3278 37.2697 67.3779C37.4103 67.4114 37.5453 67.4392 37.6859 67.4671C38.0909 67.5507 38.5015 67.6231 38.9177 67.6899C39.0752 67.7178 39.2384 67.7457 39.3959 67.768C39.8065 67.8237 40.2283 67.8682 40.6446 67.9072C40.8021 67.924 40.9596 67.9407 41.117 67.9518C41.6908 67.9908 42.2645 68.0187 42.8439 68.0187C46.6462 68.0187 50.2518 67.1105 53.4748 65.7956C53.981 65.5894 54.4816 65.3721 54.9654 65.1437C55.0104 65.1214 55.0554 65.0991 55.106 65.0768C55.5616 64.8651 56.0116 64.6478 56.4503 64.4194C56.4728 64.4082 56.5009 64.3971 56.5234 64.3804C56.9959 64.1352 57.4515 63.89 57.9015 63.6337C57.9128 63.6337 57.9184 63.6226 57.9296 63.617C58.3628 63.3719 58.779 63.1211 59.1896 62.8704C59.2177 62.8537 59.2515 62.8314 59.2796 62.8147C60.1121 62.3021 60.8996 61.7784 61.6252 61.2713C61.6533 61.2546 61.6758 61.2323 61.7039 61.2156C62.4295 60.703 63.0989 60.2016 63.7063 59.7224C63.7288 59.7057 63.7513 59.689 63.7738 59.6723C64.3757 59.1987 64.9213 58.7474 65.3938 58.3351C65.4107 58.3183 65.4275 58.3072 65.4444 58.2905C65.6694 58.0955 65.8775 57.9116 66.0744 57.7389C66.08 57.7333 66.0913 57.7222 66.0969 57.7166C66.2994 57.5383 66.4794 57.3656 66.6481 57.2151C66.6594 57.204 66.665 57.1984 66.6762 57.1873C66.8225 57.048 66.9575 56.9198 67.0756 56.8084C67.0925 56.7917 67.1094 56.775 67.1262 56.7583C67.2444 56.6468 67.3456 56.541 67.43 56.463C67.4356 56.4574 67.4412 56.4518 67.4469 56.4462C67.52 56.3738 67.5818 56.3125 67.6212 56.268C67.6325 56.2568 67.6437 56.2457 67.6493 56.2401C67.6775 56.2122 67.7 56.1844 67.7 56.1844C67.7 56.1844 67.6718 56.1565 67.6437 56.1287C67.6325 56.1175 67.6212 56.1064 67.61 56.0897H67.5875Z\" fill=\"#00B7CE\"><\/path><path d=\"M28.544 34.9632C31.3005 34.4818 33.141 31.878 32.655 29.1476C32.1689 26.4172 29.5404 24.5941 26.7839 25.0755C24.0275 25.557 22.187 28.1607 22.673 30.8911C23.159 33.6215 25.7876 35.4447 28.544 34.9632Z\" fill=\"#00B7CE\"><\/path><path d=\"M22.7676 43.2302C24.3481 43.2302 25.625 41.9598 25.625 40.3998C25.625 38.8397 24.3425 37.5693 22.7676 37.5693C21.1926 37.5693 19.9102 38.8397 19.9102 40.3998C19.9102 41.9598 21.1926 43.2302 22.7676 43.2302Z\" fill=\"#00B7CE\"><\/path><path d=\"M46.5312 69.3224C49.4449 70.5426 54.2035 71.9132 58.3434 70.1804L54.7772 66.96C52.2517 68.0464 49.473 68.9101 46.5312 69.3224Z\" fill=\"#00B7CE\"><\/path><path d=\"M52.2799 44.4397L54.6873 39.9711C44.5233 37.6087 37.6047 41.3474 34.0273 44.2224C36.7666 43.342 39.7309 42.7793 42.8358 42.7793C46.1826 42.7793 49.3606 43.4367 52.2799 44.4397Z\" fill=\"#00B7CE\"><\/path><path d=\"M73.9081 56.1849C79.7467 49.8331 77.6036 42.1943 77.6036 42.1943L67.6758 56.1849L77.6036 70.1754C77.6036 70.1754 79.7692 61.2551 73.9081 56.1849Z\" fill=\"#00B7CE\"><\/path><\/g><defs><clippath id=\"clip0_971_6149\"><rect width=\"60\" height=\"46\" fill=\"white\" transform=\"translate(18 25)\"><\/rect><\/clippath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d47676 elementor-widget elementor-widget-heading\" data-id=\"5d47676\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default translation-block\">Prot\u00e9ction de <br> l'environment<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ebf39b8 elementor-widget elementor-widget-text-editor\" data-id=\"ebf39b8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nos sites de plong\u00e9e sont situ\u00e9s dans une zone prot\u00e9g\u00e9e Natura 2000, ce qui renforce notre engagement en faveur de la conservation et du respect de l\u2019environnement marin.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5a0345d e-con-full e-flex e-con e-child\" data-id=\"5a0345d\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb39c89 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"fb39c89\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"96\" height=\"96\" viewbox=\"0 0 96 96\" fill=\"none\"><rect width=\"96\" height=\"96\" rx=\"48\" fill=\"#EBF0F8\"><\/rect><g clip-path=\"url(#clip0_971_6165)\"><path d=\"M53.9761 43.6323C53.9761 43.6323 54.0091 43.5986 54.0257 43.5817C55.0883 42.4567 56.0297 41.0674 56.7895 39.5262C55.804 40.1618 54.6643 40.5499 53.4531 40.6006C53.354 40.6006 53.2549 40.6062 53.1558 40.6062C51.1847 40.6062 49.3403 39.7793 48.0079 38.3281C46.615 39.8525 44.655 40.6962 42.5628 40.5949C41.3626 40.5443 40.2339 40.1618 39.2539 39.5375C40.4486 41.9336 42.0838 43.9642 43.8952 45.2073V44.3579C43.8952 42.963 45.0073 41.8324 46.3728 41.8324H49.6541C51.0196 41.8324 52.1262 42.9686 52.1262 44.3579V45.2185C52.7704 44.7798 53.3925 44.2398 53.9816 43.6211L53.9761 43.6323Z\" fill=\"#00B7CE\"><\/path><path d=\"M42.6256 38.9582C44.4866 39.0482 46.2704 38.1426 47.344 36.5564C47.4927 36.3371 47.7404 36.2021 48.0047 36.2021C48.269 36.2021 48.5167 36.3371 48.6654 36.5564C49.739 38.1426 51.5118 39.0201 53.3837 38.9582C55.8668 38.8514 57.948 36.9108 58.471 34.4134C58.482 34.3459 58.4985 34.284 58.5095 34.2165C58.5701 33.8846 58.6086 33.5415 58.6086 33.1928V28.5354C58.6086 27.3374 57.6562 26.3643 56.4834 26.3643H39.5314C38.3587 26.3643 37.4062 27.3374 37.4062 28.5354V33.1928C37.4062 36.2527 39.7462 38.8345 42.6256 38.9582ZM38.4688 28.5354C38.4688 27.9392 38.9423 27.4555 39.5259 27.4555H56.4779C57.0615 27.4555 57.535 27.9392 57.535 28.5354V33.1928C57.535 35.6733 55.6521 37.7714 53.3342 37.8727H53.147C51.71 37.8727 50.3611 37.1527 49.5353 35.9377C49.1774 35.4034 48.6158 35.1052 47.9992 35.1052C47.3826 35.1052 46.821 35.4034 46.4686 35.9208C45.6372 37.147 44.2884 37.867 42.8514 37.867H42.6642C40.3463 37.7658 38.4633 35.6677 38.4633 33.1872V28.5298L38.4688 28.5354Z\" fill=\"#00B7CE\"><\/path><path d=\"M42.7358 36.2302H42.8569C43.7653 36.2302 44.6187 35.7746 45.1418 35.004C45.7969 34.0365 46.865 33.4628 48.0047 33.4628C49.1444 33.4628 50.207 34.0365 50.8567 34.9927C51.3852 35.7746 52.2386 36.2358 53.1525 36.2358H53.2792C54.7382 36.1683 55.9329 34.8071 55.9329 33.1984V29.1035H40.082V33.1984C40.082 34.8127 41.2768 36.1739 42.7413 36.2358L42.7358 36.2302Z\" fill=\"#00B7CE\"><\/path><path d=\"M56.4773 24.7217C56.7746 24.7217 57.0609 24.7667 57.3361 24.8342C55.4587 20.6662 51.9241 18 48.004 18C44.084 18 40.5493 20.6662 38.6719 24.8342C38.9472 24.7667 39.2335 24.7217 39.5308 24.7217H56.4828H56.4773Z\" fill=\"#00B7CE\"><\/path><path d=\"M58.7109 52.295L67.6412 58.8086C68.1036 59.1461 68.5331 59.5285 68.9405 59.9279V56.1874C68.9405 52.9081 66.3308 50.2363 63.1155 50.2363C61.4087 50.2363 59.8121 50.9957 58.7109 52.295Z\" fill=\"#00B7CE\"><\/path><path d=\"M64.9242 48.824V47.4797C64.9242 46.4616 64.1149 45.6348 63.1184 45.6348C62.1218 45.6348 61.3125 46.4616 61.3125 47.4797V48.8184C61.8961 48.6665 62.5017 48.5934 63.1184 48.5934C63.735 48.5934 64.3461 48.6834 64.9242 48.8297V48.824Z\" fill=\"#00B7CE\"><\/path><path d=\"M37.2882 52.295C36.187 50.9957 34.5849 50.2363 32.8836 50.2363C29.6738 50.2363 27.0586 52.9025 27.0586 56.1874V59.9279C27.466 59.5285 27.89 59.1517 28.3579 58.8086L37.2882 52.295Z\" fill=\"#00B7CE\"><\/path><path d=\"M46.3589 43.4863H49.6458C50.1248 43.4863 50.5102 43.8801 50.5102 44.3694V46.3494C50.5102 46.8387 50.1248 47.2325 49.6458 47.2325H46.3644C45.8854 47.2325 45.5 46.8331 45.5 46.3494V44.3694C45.5 43.8801 45.8854 43.4863 46.3644 43.4863H46.3589Z\" fill=\"#00B7CE\"><\/path><path d=\"M53.757 50.275V46.0508C53.1789 46.512 52.5733 46.9058 51.9567 47.232C51.6373 48.1095 50.8555 48.7507 49.9141 48.8576C50.4536 50.4663 51.3786 52.3225 52.7605 52.165C53.3221 52.0975 53.9112 51.7487 54.4893 51.2312L54.0984 50.9444C53.8892 50.7925 53.7625 50.5394 53.7625 50.275H53.757Z\" fill=\"#00B7CE\"><\/path><path d=\"M66.7063 60.1463L55.7995 52.1872C58.1009 49.926 59.9288 45.803 60.3252 43.12H62.3127V44.0987C62.5715 44.0368 62.8413 43.9918 63.1166 43.9918C63.3919 43.9918 63.6616 44.0368 63.9204 44.0987V43.12H65.0436C65.4895 43.12 65.8474 42.7544 65.8474 42.2988C65.8474 41.8432 65.4895 41.4775 65.0436 41.4775H59.5929C59.1635 41.4775 58.8056 41.8263 58.7891 42.2706C58.6955 44.8018 56.6584 49.296 54.4892 51.2366L55.7995 52.1928C54.9021 53.0759 53.9331 53.6834 52.9476 53.8015C52.8264 53.8128 52.7053 53.824 52.5787 53.824C51.1913 53.824 49.4515 52.8622 48.2347 48.8798H47.7777C46.561 52.8622 44.8212 53.824 43.4337 53.824C43.3071 53.824 43.186 53.8184 43.0649 53.8015C42.0738 53.6834 41.1103 53.0759 40.2129 52.1928L41.5233 51.2366C39.354 49.296 37.3169 44.8018 37.2233 42.2706C37.2068 41.8319 36.8489 41.4775 36.4195 41.4775H30.9634C30.5174 41.4775 30.1595 41.8432 30.1595 42.2988C30.1595 42.7544 30.5174 43.12 30.9634 43.12H32.092V44.0987C32.3508 44.0368 32.6206 43.9918 32.8959 43.9918C33.1711 43.9918 33.4409 44.0368 33.6997 44.0987V43.12H35.6872C36.0837 45.803 37.906 49.926 40.2129 52.1872L29.3062 60.1463C26.6139 62.1094 25.0117 65.2987 25.0117 68.6736V77.9939C26.2395 77.9264 28.651 77.8758 33.4409 77.8589V67.9311C33.4409 67.4755 33.7988 67.1099 34.2448 67.1099C34.6907 67.1099 35.0486 67.4755 35.0486 67.9311V77.8533C37.1793 77.8533 39.7064 77.8533 42.7235 77.8533L60.9694 69.9223V67.9311C60.9694 67.4755 61.3272 67.1099 61.7732 67.1099C62.2191 67.1099 62.577 67.4755 62.577 67.9311V70.4623V74.6753V77.932C65.2087 77.9489 68.0111 77.9658 71.0062 77.9826V68.6567C71.0062 65.2818 69.3986 62.0925 66.7118 60.1295L66.7063 60.1463Z\" fill=\"#00B7CE\"><\/path><path d=\"M46.0892 48.852C45.1478 48.7451 44.366 48.0983 44.0466 47.2152C43.43 46.8889 42.8244 46.4952 42.2463 46.0283V50.2694C42.2463 50.5338 42.1197 50.7869 41.9104 50.9388L41.5195 51.2257C42.0976 51.7431 42.6867 52.0919 43.2483 52.1594C44.6247 52.3112 45.5497 50.4607 46.0948 48.852H46.0892Z\" fill=\"#00B7CE\"><\/path><path d=\"M52.6659 77.8929L60.9575 74.1636V71.7168L46.7969 77.8704C48.6082 77.876 50.5573 77.8816 52.6659 77.8929Z\" fill=\"#00B7CE\"><\/path><path d=\"M34.6977 48.8184V47.4797C34.6977 46.4616 33.8883 45.6348 32.8918 45.6348C31.8953 45.6348 31.0859 46.4616 31.0859 47.4797V48.824C31.664 48.6778 32.2697 48.5878 32.8918 48.5878C33.5139 48.5878 34.1141 48.6665 34.6977 48.8128V48.8184Z\" fill=\"#00B7CE\"><\/path><path d=\"M60.9635 77.9382V75.9639L56.625 77.9157C58.0124 77.9213 59.4604 77.9326 60.9635 77.9382Z\" fill=\"#00B7CE\"><\/path><\/g><defs><clippath id=\"clip0_971_6165\"><rect width=\"46\" height=\"60\" fill=\"white\" transform=\"translate(25 18)\"><\/rect><\/clippath><\/defs><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0eacb35 elementor-widget elementor-widget-heading\" data-id=\"0eacb35\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h4 class=\"elementor-heading-title elementor-size-default translation-block\">Equipement <br> modern<\/h4>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7fc7771 elementor-widget elementor-widget-text-editor\" data-id=\"7fc7771\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous appliquons les directives des autorit\u00e9s grecques ainsi que les protocoles des fabricants (Cressi, Coltri, etc.), afin de garantir que tout l\u2019\u00e9quipement \u2014 du tuba aux bouteilles \u2014 est correctement r\u00e9vis\u00e9 et renouvel\u00e9 r\u00e9guli\u00e8rement.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-00ef53e e-con-full e-flex e-con e-parent\" data-id=\"00ef53e\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-57d69ff elementor-widget elementor-widget-template\" data-id=\"57d69ff\" data-element_type=\"widget\" data-widget_type=\"template.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-template\">\n\t\t\t\t\t<div data-elementor-type=\"container\" data-elementor-id=\"1071\" class=\"elementor elementor-1071\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t<div class=\"elementor-element elementor-element-90b876a e-con-full e-flex e-con e-child\" data-id=\"90b876a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e38b4e0 elementor-widget elementor-widget-heading\" data-id=\"e38b4e0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ce que nos h\u00f4tes dissent pour nous<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9c1f3bd e-con-full e-flex e-con e-child\" data-id=\"9c1f3bd\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d1f3b35 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"d1f3b35\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Votre opinion est inestimable. Elle nous donne la motivation et l\u2019\u00e9nergie de continuer \u00e0 faire ce que nous aimons, tout en nous inspirant \u00e0 nous am\u00e9liorer et \u00e0 progresser constamment. Merci pour votre confiance !<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-97c44bb e-con-full elementor-hidden-tablet e-flex e-con e-child\" data-id=\"97c44bb\" data-element_type=\"container\">\n\t\t<a class=\"elementor-element elementor-element-8e36fb9 e-con-full icon-container-left swiper-button-prev-slider-testimonials e-flex e-con e-child\" data-id=\"8e36fb9\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"#\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d68d599 firsticon-left elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"d68d599\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\"><polygon points=\"12.718 4.707 11.305 3.292 2.585 12 11.305 20.707 12.718 19.292 6.417 13 20 13 20 11 6.416 11 12.718 4.707\"><\/polygon><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b25af9d secondicon-left elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"b25af9d\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\"><polygon points=\"12.718 4.707 11.305 3.292 2.585 12 11.305 20.707 12.718 19.292 6.417 13 20 13 20 11 6.416 11 12.718 4.707\"><\/polygon><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<div class=\"elementor-element elementor-element-596ce37 elementor-widget elementor-widget-button\" data-id=\"596ce37\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.google.com\/maps\/place\/Dive+Greece\/@38.9557498,22.316682,448863m\/data=!3m1!1e3!4m12!1m2!2m1!1sdive+greece!3m8!1s0x14a62e6ea97e05c7:0xad1d626c20d08e8c!8m2!3d39.9270602!4d23.5877804!9m1!1b1!15sCgtkaXZlIGdyZWVjZVoNIgtkaXZlIGdyZWVjZZIBEHNjdWJhX2luc3RydWN0b3KqAT4QASoIIgRkaXZlKAAyHxABIhtgA92lilzq1oEjwkpRkiaJuDI2VAqU6x8Ws34yDxACIgtkaXZlIGdyZWVjZeABAA!16s%2Fg%2F11cn0nwyyn?entry=ttu&#038;g_ep=EgoyMDI1MDUxMy4xIKXMDSoASAFQAw%3D%3D\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"25\" height=\"26\" viewbox=\"0 0 25 26\" fill=\"none\"><g id=\"google-icon 1\" clip-path=\"url(#clip0_1058_9383)\"><path id=\"Vector\" d=\"M24.9868 13.2434C24.9868 12.1781 24.9018 11.4008 24.7177 10.5947H12.749V15.4025H19.7744C19.6328 16.5974 18.8679 18.3967 17.1682 19.6058L17.1444 19.7668L20.9286 22.7462L21.1908 22.7727C23.5987 20.5127 24.9868 17.1875 24.9868 13.2434Z\" fill=\"#4285F4\"><\/path><path id=\"Vector_2\" d=\"M12.7493 25.9106C16.1911 25.9106 19.0806 24.759 21.1911 22.7726L17.1685 19.6056C16.092 20.3686 14.6473 20.9012 12.7493 20.9012C9.37827 20.9012 6.51714 18.6412 5.49723 15.5176L5.34773 15.5305L1.41279 18.6254L1.36133 18.7708C3.4576 23.0028 7.7635 25.9106 12.7493 25.9106Z\" fill=\"#34A853\"><\/path><path id=\"Vector_3\" d=\"M5.4966 15.5175C5.22749 14.7114 5.07174 13.8477 5.07174 12.9552C5.07174 12.0627 5.22749 11.199 5.48244 10.393L5.47531 10.2213L1.49106 7.07666L1.3607 7.13968C0.496726 8.89587 0.000976562 10.868 0.000976562 12.9552C0.000976562 15.0425 0.496726 17.0145 1.3607 18.7707L5.4966 15.5175Z\" fill=\"#FBBC05\"><\/path><path id=\"Vector_4\" d=\"M12.7493 5.00937C15.143 5.00937 16.7577 6.06018 17.6784 6.93833L21.2761 3.36839C19.0665 1.28115 16.1911 0 12.7493 0C7.7635 0 3.4576 2.90773 1.36133 7.13978L5.48307 10.3931C6.51714 7.26938 9.37827 5.00937 12.7493 5.00937Z\" fill=\"#EB4335\"><\/path><\/g><defs><clippath id=\"clip0_1058_9383\"><rect width=\"25\" height=\"26\" fill=\"white\"><\/rect><\/clippath><\/defs><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Google Reviews<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a class=\"elementor-element elementor-element-1a7b1cf e-con-full icon-container-right swiper-button-next-slider-testimonials e-flex e-con e-child\" data-id=\"1a7b1cf\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\" href=\"#\">\n\t\t\t\t<div class=\"elementor-element elementor-element-821fe45 firsticon-right elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"821fe45\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\"><polygon points=\"11.293 4.707 17.586 11 4 11 4 13 17.586 13 11.293 19.293 12.707 20.707 21.414 12 12.707 3.293 11.293 4.707\"><\/polygon><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-32107d5 secondicon-right elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"32107d5\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewbox=\"0 0 24 24\"><polygon points=\"11.293 4.707 17.586 11 4 11 4 13 17.586 13 11.293 19.293 12.707 20.707 21.414 12 12.707 3.293 11.293 4.707\"><\/polygon><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-dc5590d e-con-full slider-testimonials e-flex e-con e-child\" data-id=\"dc5590d\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-818516d e-con-full swiper-container e-flex e-con e-child\" data-id=\"818516d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7d1b644 e-con-full swiper-wrapper e-flex e-con e-child\" data-id=\"7d1b644\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-8c03db7 e-con-full swiper-slide  e-flex e-con e-child\" data-id=\"8c03db7\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-edc5844 elementor-widget elementor-widget-heading\" data-id=\"edc5844\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">An experience I\u2019ll never forget!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ceff855 scrollbar-testimonial elementor-widget elementor-widget-text-editor\" data-id=\"ceff855\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div><div class=\"OA1nbd\">We had such a wonderful snorkeling trip! Emilios was super kind and helpful, providing clear explanations and professional guidance throughout. The bay was beautiful, and we really appreciated the respect shown for sea life and the animals. The pick-up service made everything easy and stress-free. All the ingredients for a perfect morning with the kids!<\/div><\/div><div class=\"svzjne\"><div class=\"LvICbd\">\u00a0<\/div><\/div><p>My experience with Dive Greece was incredible! The team was friendly, professional, and went above and beyond to make me feel comfortable. The equipment was modern, the guidance was excellent, and the dives were truly magical. I can\u2019t wait to come back!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc6f31d icon-testimonials elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"cc6f31d\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"70\" height=\"21\" viewbox=\"0 0 70 21\" fill=\"none\"><g id=\"Group 4\"><path id=\"Vector 2\" d=\"M18.3221 0L0 18.6667L23.0201 14.9333L56.3758 21L70 0L54.0268 12.1333L18.3221 0Z\" fill=\"#00B7CE\"><\/path><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7af9a6f elementor-widget elementor-widget-heading\" data-id=\"7af9a6f\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Stephanie Sunaert<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-18f5b36 e-con-full swiper-slide  e-flex e-con e-child\" data-id=\"18f5b36\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13dbfae elementor-widget elementor-widget-heading\" data-id=\"13dbfae\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Beyond expectations \u2014 simply amazing!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-447d649 scrollbar-testimonial elementor-widget elementor-widget-text-editor\" data-id=\"447d649\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"OA1nbd\">Amazing diving experience! The instructor Emilios was very professional, friendly, and made me feel safe at all times. I really liked that we were in a small group-just the instructor and us. The equipment was in excellent condition, and the dive sites were interesting with lots of marine life to see. I would highly recommend this diving company to anyone looking for an unforgettable adventure!<\/div><div data-review-id=\"Ci9DQUlRQUNvZENodHljRjlvT2tWcFdqTkxjelpvVUdWRldrMHhVV1pTY0cxWmJWRRAB\"><div class=\"acCJ4b\" data-hveid=\"27\" data-ved=\"0CBsQp70JahcKEwjwrqes5t2QAxUAAAAAHQAAAAAQEA\"><div class=\"EDblX GpHuwc\"><div class=\"k9lweb\" role=\"list\">\u00a0<\/div><\/div><\/div><\/div><p>My experience with Dive Greece was incredible! The team was friendly, professional, and went above and beyond to make me feel comfortable. The equipment was modern, the guidance was excellent, and the dives were truly magical. I can\u2019t wait to come back!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-81780da icon-testimonials elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"81780da\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"70\" height=\"21\" viewbox=\"0 0 70 21\" fill=\"none\"><g id=\"Group 4\"><path id=\"Vector 2\" d=\"M18.3221 0L0 18.6667L23.0201 14.9333L56.3758 21L70 0L54.0268 12.1333L18.3221 0Z\" fill=\"#00B7CE\"><\/path><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a16efec elementor-widget elementor-widget-heading\" data-id=\"a16efec\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Madara \u017demaite<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cab390d e-con-full swiper-slide  e-flex e-con e-child\" data-id=\"cab390d\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8b71e4 elementor-widget elementor-widget-heading\" data-id=\"e8b71e4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">The highlight of our trip!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c32f83c scrollbar-testimonial elementor-widget elementor-widget-text-editor\" data-id=\"c32f83c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"OA1nbd\">It was a wonderful experience. The sea was amazing. Anastasia was wonderful throughout the entire booking and training process. Emilios is a wonderful teacher. He was patient and informative with the children throughout the entire dive process. It was our third diving experience and the best. Thank you for everything.<\/div><div data-review-id=\"Ci9DQUlRQUNvZENodHljRjlvT25GNVkzQjNiWGRYYjJaRWRVdEhUV1JtWW0xa2FIYxAB\"><div class=\"acCJ4b\" data-hveid=\"50\" data-ved=\"0CDIQp70JahcKEwjwrqes5t2QAxUAAAAAHQAAAAAQEA\"><div class=\"EDblX GpHuwc\"><div class=\"k9lweb\" role=\"list\">\u00a0<\/div><\/div><\/div><\/div><p>My experience with Dive Greece was incredible! The team was friendly, professional, and went above and beyond to make me feel comfortable. The equipment was modern, the guidance was excellent, and the dives were truly magical. I can\u2019t wait to come back!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9874316 icon-testimonials elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"9874316\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"70\" height=\"21\" viewbox=\"0 0 70 21\" fill=\"none\"><g id=\"Group 4\"><path id=\"Vector 2\" d=\"M18.3221 0L0 18.6667L23.0201 14.9333L56.3758 21L70 0L54.0268 12.1333L18.3221 0Z\" fill=\"#00B7CE\"><\/path><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a92e77e elementor-widget elementor-widget-heading\" data-id=\"a92e77e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">A.Serhat Yan\u0131ko\u011flu<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c08f231 e-con-full swiper-slide  e-flex e-con e-child\" data-id=\"c08f231\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5ca6356 elementor-widget elementor-widget-heading\" data-id=\"5ca6356\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Unbelievable adventure! Can\u2019t wait to go again!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f87b96c scrollbar-testimonial elementor-widget elementor-widget-text-editor\" data-id=\"f87b96c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Such a wonderful way to end my vacation &#8211; Emilios is an amazing instructor and I felt safe and supported throughout my two dives. He helped me a lot with making the most of my experience and getting better at diving in general.<br \/><br \/>Definitely woud recommend and dive here again!<\/p><p>My experience with Dive Greece was incredible! The team was friendly, professional, and went above and beyond to make me feel comfortable. The equipment was modern, the guidance was excellent, and the dives were truly magical. I can\u2019t wait to come back!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fd6de8b icon-testimonials elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"fd6de8b\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"70\" height=\"21\" viewbox=\"0 0 70 21\" fill=\"none\"><g id=\"Group 4\"><path id=\"Vector 2\" d=\"M18.3221 0L0 18.6667L23.0201 14.9333L56.3758 21L70 0L54.0268 12.1333L18.3221 0Z\" fill=\"#00B7CE\"><\/path><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e0c0e5c elementor-widget elementor-widget-heading\" data-id=\"e0c0e5c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Jasmin Kiechle<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1fee353 e-con-full swiper-slide  e-flex e-con e-child\" data-id=\"1fee353\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-83bb3ff elementor-widget elementor-widget-heading\" data-id=\"83bb3ff\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Absolutely incredible from start to finish!<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4993b5a scrollbar-testimonial elementor-widget elementor-widget-text-editor\" data-id=\"4993b5a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Diving with Emilios was fantastic. His calm and friendly manner puts you at ease before and during the dive. The equipment was in excellent condition. Thank you very much. We hope to come back soon.<\/p><p>My experience with Dive Greece was incredible! The team was friendly, professional, and went above and beyond to make me feel comfortable. The equipment was modern, the guidance was excellent, and the dives were truly magical. I can\u2019t wait to come back!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9a1b20 icon-testimonials elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"c9a1b20\" data-element_type=\"widget\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<div class=\"elementor-icon\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"70\" height=\"21\" viewbox=\"0 0 70 21\" fill=\"none\"><g id=\"Group 4\"><path id=\"Vector 2\" d=\"M18.3221 0L0 18.6667L23.0201 14.9333L56.3758 21L70 0L54.0268 12.1333L18.3221 0Z\" fill=\"#00B7CE\"><\/path><\/g><\/svg>\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8507bc0 elementor-widget elementor-widget-heading\" data-id=\"8507bc0\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Annina Gemperle<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0466e64 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-widget elementor-widget-html\" data-id=\"0466e64\" data-element_type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<style>\n    \n.icon-testimonials    .elementor-icon-wrapper{\n    display: flex\n}\n\n\n .icon-testimonials svg {\n    width: clamp(3.125rem, 1.6934rem + 2.2346vw, 4.375rem) !important;\n    height: auto !important;\n}\n\n.scrollbar-testimonial {\n    \/*130-105*\/\n    max-height: clamp(6.5625rem, 4.773rem + 2.7933vw, 8.125rem);\n    overflow-x: hidden;\n    overflow-y: auto; \/* \u03b5\u03bc\u03c6\u03b1\u03bd\u03af\u03b6\u03b5\u03b9 scrollbar \u03bc\u03cc\u03bd\u03bf \u03cc\u03c4\u03b1\u03bd \u03c7\u03c1\u03b5\u03b9\u03ac\u03b6\u03b5\u03c4\u03b1\u03b9 *\/\n}\n\n\/* Custom scrollbar styles *\/\n.scrollbar-testimonial::-webkit-scrollbar {\n    width: 5px;\n    border-radius: 3px;\n}\n\n.scrollbar-testimonial::-webkit-scrollbar-track {\n    background: #ccf1f5;\n    border-radius: 3px;\n}\n\n.scrollbar-testimonial::-webkit-scrollbar-thumb {\n    background: #00b7ce;\n    border-radius: 3px;\n}\n\n\n<\/style>\n\n<script>\ndocument.addEventListener(\"DOMContentLoaded\", function () {\n    var mySwiper = new Swiper(\".slider-testimonials .swiper-container\", {\n        centeredSlides: false,\n        loop: false,\n         navigation: {\n            nextEl: \".swiper-button-next-slider-testimonials\",\n            prevEl: \".swiper-button-prev-slider-testimonials\",\n        },\n       \n        slidesPerView: 1.2,\n        spaceBetween: 10,\n        slidesPerGroup: 1,\n        speed: 400,\n        breakpoints: {\n            768: {\n            \n                slidesPerView: 2.6,\n                slidesPerGroup: 1,\n                spaceBetween: 20,\n            },\n               950: {\n            \n                slidesPerView: 3.6,\n                slidesPerGroup: 1,\n                spaceBetween: 20,\n            },\n                 1250: {\n            \n                slidesPerView: 4.8,\n                slidesPerGroup: 1,\n                spaceBetween: 20,\n            },\n        },\n \n    });\n\n\n});\n\n\n<\/script>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>.elementor-807 .elementor-element.elementor-element-ad6c42e{&#8211;display:flex;&#8211;min-height:92vh;&#8211;flex-direction:column;&#8211;container-widget-width:calc( ( 1 &#8211; var( &#8211;container-widget-flex-grow ) ) * 100% );&#8211;container-widget-height:initial;&#8211;container-widget-flex-grow:0;&#8211;container-widget-align-self:initial;&#8211;flex-wrap-mobile:wrap;&#8211;justify-content:center;&#8211;align-items:flex-start;&#8211;gap:1.25vw 1.25vw;&#8211;row-gap:1.25vw;&#8211;column-gap:1.25vw;&#8211;overlay-opacity:1;&#8211;padding-top:0;&#8211;padding-bottom:0;&#8211;padding-left:clamp(2.5rem, -3.2263rem + 8.9385vw, 7.5rem);&#8211;padding-right:clamp(2.5rem, -3.2263rem + 8.9385vw, 7.5rem);}.elementor-807 .elementor-element.elementor-element-ad6c42e:not(.elementor-motion-effects-element-type-background), .elementor-807 .elementor-element.elementor-element-ad6c42e &gt; .elementor-motion-effects-container &gt; .elementor-motion-effects-layer{background-position:center center;background-repeat:no-repeat;background-size:cover;}.elementor-807 .elementor-element.elementor-element-ad6c42e::before, .elementor-807 .elementor-element.elementor-element-ad6c42e &gt; .elementor-background-video-container::before, .elementor-807 .elementor-element.elementor-element-ad6c42e &gt; .e-con-inner &gt; .elementor-background-video-container::before, .elementor-807 .elementor-element.elementor-element-ad6c42e &gt; .elementor-background-slideshow::before, .elementor-807 .elementor-element.elementor-element-ad6c42e &gt; .e-con-inner &gt; .elementor-background-slideshow::before, .elementor-807 .elementor-element.elementor-element-ad6c42e &gt; .elementor-motion-effects-container &gt; [&hellip;]<\/p>","protected":false},"author":7,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-58","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>About Dive-greece | PADI Dive Centre in Loutra, Kassandra<\/title>\n<meta name=\"description\" content=\"Meet our multilingual, experienced team and discover our safety\u2011first approach in a stunning Natura 2000 area. Learn why divers choose Dive-greece in Halkidiki.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/dive-greece.gr\/fr\/about-us\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"About Dive-greece | PADI Dive Centre in Loutra, Kassandra\" \/>\n<meta property=\"og:description\" content=\"Meet our multilingual, experienced team and discover our safety\u2011first approach in a stunning Natura 2000 area. Learn why divers choose Dive-greece in Halkidiki.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/dive-greece.gr\/fr\/about-us\/\" \/>\n<meta property=\"og:site_name\" content=\"Dive Greece\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/divegreece16\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-22T05:06:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/dive-greece.gr\/wp-content\/uploads\/padi-logo.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/dive-greece.gr\/about-us\/\",\"url\":\"https:\/\/dive-greece.gr\/about-us\/\",\"name\":\"About Dive-greece | PADI Dive Centre in Loutra, Kassandra\",\"isPartOf\":{\"@id\":\"https:\/\/dive-greece.gr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/dive-greece.gr\/about-us\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/dive-greece.gr\/about-us\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/dive-greece.gr\/wp-content\/uploads\/padi-logo.jpg\",\"datePublished\":\"2025-05-12T13:59:21+00:00\",\"dateModified\":\"2025-12-22T05:06:11+00:00\",\"description\":\"Meet our multilingual, experienced team and discover our safety\u2011first approach in a stunning Natura 2000 area. Learn why divers choose Dive-greece in Halkidiki.\",\"breadcrumb\":{\"@id\":\"https:\/\/dive-greece.gr\/about-us\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/dive-greece.gr\/about-us\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dive-greece.gr\/about-us\/#primaryimage\",\"url\":\"https:\/\/dive-greece.gr\/wp-content\/uploads\/padi-logo.jpg\",\"contentUrl\":\"https:\/\/dive-greece.gr\/wp-content\/uploads\/padi-logo.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/dive-greece.gr\/about-us\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/dive-greece.gr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"About us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/dive-greece.gr\/#website\",\"url\":\"https:\/\/dive-greece.gr\/\",\"name\":\"Dive Greece\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/dive-greece.gr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/dive-greece.gr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/dive-greece.gr\/#organization\",\"name\":\"Dive Greece\",\"url\":\"https:\/\/dive-greece.gr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/dive-greece.gr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/dive-greece.gr\/wp-content\/uploads\/logo-dive-greece.png\",\"contentUrl\":\"https:\/\/dive-greece.gr\/wp-content\/uploads\/logo-dive-greece.png\",\"width\":264,\"height\":136,\"caption\":\"Dive Greece\"},\"image\":{\"@id\":\"https:\/\/dive-greece.gr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/divegreece16\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"About Dive-greece | PADI Dive Centre in Loutra, Kassandra","description":"Meet our multilingual, experienced team and discover our safety\u2011first approach in a stunning Natura 2000 area. Learn why divers choose Dive-greece in Halkidiki.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/dive-greece.gr\/fr\/about-us\/","og_locale":"fr_FR","og_type":"article","og_title":"About Dive-greece | PADI Dive Centre in Loutra, Kassandra","og_description":"Meet our multilingual, experienced team and discover our safety\u2011first approach in a stunning Natura 2000 area. Learn why divers choose Dive-greece in Halkidiki.","og_url":"https:\/\/dive-greece.gr\/fr\/about-us\/","og_site_name":"Dive Greece","article_publisher":"https:\/\/www.facebook.com\/divegreece16\/","article_modified_time":"2025-12-22T05:06:11+00:00","og_image":[{"url":"https:\/\/dive-greece.gr\/wp-content\/uploads\/padi-logo.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/dive-greece.gr\/about-us\/","url":"https:\/\/dive-greece.gr\/about-us\/","name":"About Dive-greece | PADI Dive Centre in Loutra, Kassandra","isPartOf":{"@id":"https:\/\/dive-greece.gr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/dive-greece.gr\/about-us\/#primaryimage"},"image":{"@id":"https:\/\/dive-greece.gr\/about-us\/#primaryimage"},"thumbnailUrl":"https:\/\/dive-greece.gr\/wp-content\/uploads\/padi-logo.jpg","datePublished":"2025-05-12T13:59:21+00:00","dateModified":"2025-12-22T05:06:11+00:00","description":"Meet our multilingual, experienced team and discover our safety\u2011first approach in a stunning Natura 2000 area. Learn why divers choose Dive-greece in Halkidiki.","breadcrumb":{"@id":"https:\/\/dive-greece.gr\/about-us\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/dive-greece.gr\/about-us\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dive-greece.gr\/about-us\/#primaryimage","url":"https:\/\/dive-greece.gr\/wp-content\/uploads\/padi-logo.jpg","contentUrl":"https:\/\/dive-greece.gr\/wp-content\/uploads\/padi-logo.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/dive-greece.gr\/about-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/dive-greece.gr\/"},{"@type":"ListItem","position":2,"name":"About us"}]},{"@type":"WebSite","@id":"https:\/\/dive-greece.gr\/#website","url":"https:\/\/dive-greece.gr\/","name":"Dive Greece","description":"","publisher":{"@id":"https:\/\/dive-greece.gr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/dive-greece.gr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/dive-greece.gr\/#organization","name":"Dive Greece","url":"https:\/\/dive-greece.gr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/dive-greece.gr\/#\/schema\/logo\/image\/","url":"https:\/\/dive-greece.gr\/wp-content\/uploads\/logo-dive-greece.png","contentUrl":"https:\/\/dive-greece.gr\/wp-content\/uploads\/logo-dive-greece.png","width":264,"height":136,"caption":"Dive Greece"},"image":{"@id":"https:\/\/dive-greece.gr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/divegreece16\/"]}]}},"_links":{"self":[{"href":"https:\/\/dive-greece.gr\/fr\/wp-json\/wp\/v2\/pages\/58","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dive-greece.gr\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/dive-greece.gr\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/dive-greece.gr\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/dive-greece.gr\/fr\/wp-json\/wp\/v2\/comments?post=58"}],"version-history":[{"count":171,"href":"https:\/\/dive-greece.gr\/fr\/wp-json\/wp\/v2\/pages\/58\/revisions"}],"predecessor-version":[{"id":2900,"href":"https:\/\/dive-greece.gr\/fr\/wp-json\/wp\/v2\/pages\/58\/revisions\/2900"}],"wp:attachment":[{"href":"https:\/\/dive-greece.gr\/fr\/wp-json\/wp\/v2\/media?parent=58"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}